{"id":1324,"date":"2021-10-06T18:13:50","date_gmt":"2021-10-06T21:13:50","guid":{"rendered":"https:\/\/www.odonto.ufmg.br\/teleodonto\/?page_id=1324"},"modified":"2023-03-03T13:09:11","modified_gmt":"2023-03-03T16:09:11","slug":"videoteca","status":"publish","type":"page","link":"https:\/\/www.odonto.ufmg.br\/teleodontologia\/videoteca\/","title":{"rendered":"Videoteca"},"content":{"rendered":"<div id='av_section_1'  class='avia-section av-2wybjg-e8cc2440a17008f3ff3822be2d39be09 main_color avia-section-small avia-no-border-styling  avia-builder-el-0  el_before_av_one_fourth  avia-builder-el-first  avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><main  role=\"main\" itemprop=\"mainContentOfPage\"  class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-1324'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-kug0e4i4-ce072c68caf1c5b3d5b2e096c5ecb903\">\n#top .av-special-heading.av-kug0e4i4-ce072c68caf1c5b3d5b2e096c5ecb903{\npadding-bottom:10px;\ncolor:#000000;\nfont-size:40px;\n}\nbody .av-special-heading.av-kug0e4i4-ce072c68caf1c5b3d5b2e096c5ecb903 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n#top #wrap_all .av-special-heading.av-kug0e4i4-ce072c68caf1c5b3d5b2e096c5ecb903 .av-special-heading-tag{\nfont-size:40px;\n}\n.av-special-heading.av-kug0e4i4-ce072c68caf1c5b3d5b2e096c5ecb903 .special-heading-inner-border{\nborder-color:#000000;\n}\n.av-special-heading.av-kug0e4i4-ce072c68caf1c5b3d5b2e096c5ecb903 .av-subheading{\nfont-size:15px;\n}\n\n@media only screen and (min-width: 480px) and (max-width: 767px){ \n#top #wrap_all .av-special-heading.av-kug0e4i4-ce072c68caf1c5b3d5b2e096c5ecb903 .av-special-heading-tag{\nfont-size:0.8em;\n}\n}\n\n@media only screen and (max-width: 479px){ \n#top #wrap_all .av-special-heading.av-kug0e4i4-ce072c68caf1c5b3d5b2e096c5ecb903 .av-special-heading-tag{\nfont-size:0.8em;\n}\n}\n<\/style>\n<div  class='av-special-heading av-kug0e4i4-ce072c68caf1c5b3d5b2e096c5ecb903 av-special-heading-h1 custom-color-heading blockquote modern-quote modern-centered  avia-builder-el-1  el_before_av_hr  avia-builder-el-first  av-inherit-size'><h1 class='av-special-heading-tag '  itemprop=\"headline\"  >Web Confer\u00eancias<\/h1><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-kugzxuvo-68ca6af75ea7fbec8dc96f49729d192c\">\n#top .hr.av-kugzxuvo-68ca6af75ea7fbec8dc96f49729d192c{\nmargin-top:0px;\nmargin-bottom:5px;\n}\n.hr.av-kugzxuvo-68ca6af75ea7fbec8dc96f49729d192c .hr-inner{\nwidth:100px;\nborder-color:#02989e;\n}\n<\/style>\n<div  class='hr av-kugzxuvo-68ca6af75ea7fbec8dc96f49729d192c hr-custom  avia-builder-el-2  el_after_av_heading  avia-builder-el-last  hr-center hr-icon-no'><span class='hr-inner inner-border-av-border-fat'><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n<\/div><\/div><\/main><!-- close content main element --><\/div><\/div><div id='after_section_1'  class='main_color av_default_container_wrap container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-1324'><div class='entry-content-wrapper clearfix'>\n<div class='flex_column_table av-ks0ebg-bc4914916579db35be9e7cd87f8ac879 sc-av_one_fourth av-equal-height-column-flextable'><div  class='flex_column av-ks0ebg-bc4914916579db35be9e7cd87f8ac879 av_one_fourth  avia-builder-el-3  el_after_av_section  el_before_av_one_fourth  avia-builder-el-first  first flex_column_table_cell av-equal-height-column av-align-top av-animated-generic left-to-right  '     ><article  class='iconbox iconbox_top av-kyu7jtyl-8d604a7e39cd293dd7bf75870929baa2  avia-builder-el-4  avia-builder-el-no-sibling  main_color'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconbox_content\"><header class=\"entry-content-header\" aria-label=\"Icon: Odontopediatria\"><a href='https:\/\/www.odonto.ufmg.br\/teleodontologia\/odontopediatria\/' title='Odontopediatria' aria-label='Odontopediatria'  class='iconbox_icon heading-color avia-iconfont avia-font-entypo-fontello' data-av_icon='\ue828' data-av_iconfont='entypo-fontello' title=\"Odontopediatria\" desc=\"Odontopediatria\" ><\/a><h3 class='iconbox_content_title '  itemprop=\"headline\" ><a href='https:\/\/www.odonto.ufmg.br\/teleodontologia\/odontopediatria\/' title='Odontopediatria' >Odontopediatria<\/a><\/h3><\/header><div class='iconbox_content_container '  itemprop=\"text\" ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><\/div>\n<div class='av-flex-placeholder'><\/div><div  class='flex_column av-irwdj0-3f2c45bd6b6e2cee636db7ea9927dd79 av_one_fourth  avia-builder-el-5  el_after_av_one_fourth  el_before_av_one_fourth  flex_column_table_cell av-equal-height-column av-align-top av-animated-generic left-to-right  '     ><article  class='iconbox iconbox_top av-kyu7kce8-d99e686e8054fdbe96af479dd072fe77  avia-builder-el-6  avia-builder-el-no-sibling  main_color'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconbox_content\"><header class=\"entry-content-header\" aria-label=\"Icon: Aten\u00e7\u00e3o Integral ao Idoso\"><a href='https:\/\/www.odonto.ufmg.br\/teleodontologia\/atencao-integral-ao-idoso\/' title='Aten\u00e7\u00e3o Integral ao Idoso' aria-label='Aten\u00e7\u00e3o Integral ao Idoso'  class='iconbox_icon heading-color avia-iconfont avia-font-entypo-fontello' data-av_icon='\ue828' data-av_iconfont='entypo-fontello' title=\"Aten\u00e7\u00e3o Integral ao Idoso\" desc=\"Aten\u00e7\u00e3o Integral ao Idoso\" ><\/a><h3 class='iconbox_content_title '  itemprop=\"headline\" ><a href='https:\/\/www.odonto.ufmg.br\/teleodontologia\/atencao-integral-ao-idoso\/' title='Aten\u00e7\u00e3o Integral ao Idoso' >Aten\u00e7\u00e3o Integral ao Idoso<\/a><\/h3><\/header><div class='iconbox_content_container '  itemprop=\"text\" ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><\/div>\n<div class='av-flex-placeholder'><\/div><div  class='flex_column av-gwtgss-0369dff59762f14058d1450454be7841 av_one_fourth  avia-builder-el-7  el_after_av_one_fourth  el_before_av_one_fourth  flex_column_table_cell av-equal-height-column av-align-top av-animated-generic left-to-right  '     ><article  class='iconbox iconbox_top av-kyu7kkao-202a23cfe305df5860acfe4e8955bfa2  avia-builder-el-8  avia-builder-el-no-sibling  main_color'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconbox_content\"><header class=\"entry-content-header\" aria-label=\"Icon: Dent\u00edstica\"><a href='https:\/\/www.odonto.ufmg.br\/teleodontologia\/dentistica\/' title='Dent\u00edstica' aria-label='Dent\u00edstica'  class='iconbox_icon heading-color avia-iconfont avia-font-entypo-fontello' data-av_icon='\ue828' data-av_iconfont='entypo-fontello' title=\"Dent\u00edstica\" desc=\"Dent\u00edstica\" ><\/a><h3 class='iconbox_content_title '  itemprop=\"headline\" ><a href='https:\/\/www.odonto.ufmg.br\/teleodontologia\/dentistica\/' title='Dent\u00edstica' >Dent\u00edstica<\/a><\/h3><\/header><div class='iconbox_content_container '  itemprop=\"text\" ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><\/div>\n<div class='av-flex-placeholder'><\/div><div  class='flex_column av-36hong-97ea27f862b6a479009ed90a33f05e09 av_one_fourth  avia-builder-el-9  el_after_av_one_fourth  el_before_av_one_fourth  flex_column_table_cell av-equal-height-column av-align-top av-animated-generic left-to-right  '     ><article  class='iconbox iconbox_top av-lesq0wa1-2417316fd806df38ea39d0fbb7e7a848  avia-builder-el-10  avia-builder-el-no-sibling  main_color'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconbox_content\"><header class=\"entry-content-header\" aria-label=\"Icon: Disfun\u00e7\u00e3o Temporomandibular e Dor Orofacial\"><a href='https:\/\/www.odonto.ufmg.br\/teleodontologia\/disfuncoes-temporomandibulares-e-dor-orofacial\/' title='Disfun\u00e7\u00e3o Temporomandibular e Dor Orofacial' aria-label='Disfun\u00e7\u00e3o Temporomandibular e Dor Orofacial'  class='iconbox_icon heading-color avia-iconfont avia-font-entypo-fontello' data-av_icon='\ue828' data-av_iconfont='entypo-fontello' title=\"Disfun\u00e7\u00e3o Temporomandibular e Dor Orofacial\" desc=\"Disfun\u00e7\u00e3o Temporomandibular e Dor Orofacial\" ><\/a><h3 class='iconbox_content_title '  itemprop=\"headline\" ><a href='https:\/\/www.odonto.ufmg.br\/teleodontologia\/disfuncoes-temporomandibulares-e-dor-orofacial\/' title='Disfun\u00e7\u00e3o Temporomandibular e Dor Orofacial' >Disfun\u00e7\u00e3o Temporomandibular e Dor Orofacial<\/a><\/h3><\/header><div class='iconbox_content_container '  itemprop=\"text\" ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><\/div><\/div><!--close column table wrapper. Autoclose: 1 -->\n<div  class='flex_column av-fp23u4-91d351a2707c17bdef72fa8264674e04 av_one_fourth  avia-builder-el-11  el_after_av_one_fourth  el_before_av_one_fourth  first flex_column_div av-animated-generic left-to-right  column-top-margin'     ><article  class='iconbox iconbox_top av-kyu7lpom-1a09abbdda146b0ad760e02ea79a8800  avia-builder-el-12  avia-builder-el-no-sibling  main_color'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconbox_content\"><header class=\"entry-content-header\" aria-label=\"Icon: Endodontia \"><a href='https:\/\/www.odonto.ufmg.br\/teleodontologia\/endodontia\/' title='Endodontia ' aria-label='Endodontia '  class='iconbox_icon heading-color avia-iconfont avia-font-entypo-fontello' data-av_icon='\ue828' data-av_iconfont='entypo-fontello' title=\"Endodontia \" desc=\"Endodontia \" ><\/a><h3 class='iconbox_content_title '  itemprop=\"headline\" ><a href='https:\/\/www.odonto.ufmg.br\/teleodontologia\/endodontia\/' title='Endodontia ' >Endodontia <\/a><\/h3><\/header><div class='iconbox_content_container '  itemprop=\"text\" ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><\/div>\n<div  class='flex_column av-esthfg-e27a61b504fff7947b179a3bb7b588be av_one_fourth  avia-builder-el-13  el_after_av_one_fourth  el_before_av_one_fourth  flex_column_div av-animated-generic right-to-left  column-top-margin'     ><article  class='iconbox iconbox_top av-kyu7lznk-8af2be45e14b2b04a1239cfe0b693f0a  avia-builder-el-14  avia-builder-el-no-sibling  main_color'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconbox_content\"><header class=\"entry-content-header\" aria-label=\"Icon: Periodontia\"><a href='https:\/\/www.odonto.ufmg.br\/teleodontologia\/periodontia\/' title='Periodontia' aria-label='Periodontia'  class='iconbox_icon heading-color avia-iconfont avia-font-entypo-fontello' data-av_icon='\ue828' data-av_iconfont='entypo-fontello' title=\"Periodontia\" desc=\"Periodontia\" ><\/a><h3 class='iconbox_content_title '  itemprop=\"headline\" ><a href='https:\/\/www.odonto.ufmg.br\/teleodontologia\/periodontia\/' title='Periodontia' >Periodontia<\/a><\/h3><\/header><div class='iconbox_content_container '  itemprop=\"text\" ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><\/div>\n<div  class='flex_column av-cb7bgc-dc0a8493242df346aea3bebc9b60b86f av_one_fourth  avia-builder-el-15  el_after_av_one_fourth  el_before_av_one_fourth  flex_column_div av-animated-generic right-to-left  column-top-margin'     ><article  class='iconbox iconbox_top av-kyu7p3uv-fa4b1dd4b9073dd155b8d34013a98f25  avia-builder-el-16  avia-builder-el-no-sibling  main_color'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconbox_content\"><header class=\"entry-content-header\" aria-label=\"Icon: Cirurgia, Anestesiologia e Farmacologia \"><a href='https:\/\/www.odonto.ufmg.br\/teleodontologia\/cirurgia-anestesiologia-e-farmacologia\/' title='Cirurgia, Anestesiologia e Farmacologia ' aria-label='Cirurgia, Anestesiologia e Farmacologia '  class='iconbox_icon heading-color avia-iconfont avia-font-entypo-fontello' data-av_icon='\ue828' data-av_iconfont='entypo-fontello' title=\"Cirurgia, Anestesiologia e Farmacologia \" desc=\"Cirurgia, Anestesiologia e Farmacologia \" ><\/a><h3 class='iconbox_content_title '  itemprop=\"headline\" ><a href='https:\/\/www.odonto.ufmg.br\/teleodontologia\/cirurgia-anestesiologia-e-farmacologia\/' title='Cirurgia, Anestesiologia e Farmacologia ' >Cirurgia, Anestesiologia e Farmacologia <\/a><\/h3><\/header><div class='iconbox_content_container '  itemprop=\"text\" ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><\/div>\n<div  class='flex_column av-abysx8-c6d2e5c105adbce209802e2e2f1959b4 av_one_fourth  avia-builder-el-17  el_after_av_one_fourth  el_before_av_one_fourth  flex_column_div av-animated-generic right-to-left  column-top-margin'     ><article  class='iconbox iconbox_top av-kyu7pddr-95e8dcd601af854f2c883dc04a520a50  avia-builder-el-18  avia-builder-el-no-sibling  main_color'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconbox_content\"><header class=\"entry-content-header\" aria-label=\"Icon: Patologia Bucal e Estomatologia\"><a href='https:\/\/www.odonto.ufmg.br\/teleodontologia\/patologia-bucal-e-estomatologia\/' title='Patologia Bucal e Estomatologia' aria-label='Patologia Bucal e Estomatologia'  class='iconbox_icon heading-color avia-iconfont avia-font-entypo-fontello' data-av_icon='\ue828' data-av_iconfont='entypo-fontello' title=\"Patologia Bucal e Estomatologia\" desc=\"Patologia Bucal e Estomatologia\" ><\/a><h3 class='iconbox_content_title '  itemprop=\"headline\" ><a href='https:\/\/www.odonto.ufmg.br\/teleodontologia\/patologia-bucal-e-estomatologia\/' title='Patologia Bucal e Estomatologia' >Patologia Bucal e Estomatologia<\/a><\/h3><\/header><div class='iconbox_content_container '  itemprop=\"text\" ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><\/div>\n<div  class='flex_column av-9ph1os-eee3f7019ef42a93b99c7ea45ca59ed9 av_one_fourth  avia-builder-el-19  el_after_av_one_fourth  el_before_av_one_fourth  first flex_column_div av-animated-generic right-to-left  column-top-margin'     ><article  class='iconbox iconbox_top av-kyu7pnvz-23e556b1d3987b1713dfd6c838e37199  avia-builder-el-20  avia-builder-el-no-sibling  main_color'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconbox_content\"><header class=\"entry-content-header\" aria-label=\"Icon: Traumatismos Dent\u00e1rios \"><a href='https:\/\/www.odonto.ufmg.br\/teleodontologia\/traumatismos-dentarios\/' title='Traumatismos Dent\u00e1rios ' aria-label='Traumatismos Dent\u00e1rios '  class='iconbox_icon heading-color avia-iconfont avia-font-entypo-fontello' data-av_icon='\ue828' data-av_iconfont='entypo-fontello' title=\"Traumatismos Dent\u00e1rios \" desc=\"Traumatismos Dent\u00e1rios \" ><\/a><h3 class='iconbox_content_title '  itemprop=\"headline\" ><a href='https:\/\/www.odonto.ufmg.br\/teleodontologia\/traumatismos-dentarios\/' title='Traumatismos Dent\u00e1rios ' >Traumatismos Dent\u00e1rios <\/a><\/h3><\/header><div class='iconbox_content_container '  itemprop=\"text\" ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><\/div>\n<div  class='flex_column av-pl0vw-210ae8b44524ebb99208ae8d7af48e29 av_one_fourth  avia-builder-el-21  el_after_av_one_fourth  el_before_av_one_fourth  flex_column_div av-animated-generic bottom-to-top  column-top-margin'     ><article  class='iconbox iconbox_top av-kyu7qazi-bc21dcea571da548c5b3cf6c9e528365  avia-builder-el-22  avia-builder-el-no-sibling  main_color'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconbox_content\"><header class=\"entry-content-header\" aria-label=\"Icon: Sa\u00fade Coletiva \"><a href='https:\/\/www.odonto.ufmg.br\/teleodontologia\/saude-coletiva\/' title='Sa\u00fade Coletiva ' aria-label='Sa\u00fade Coletiva '  class='iconbox_icon heading-color avia-iconfont avia-font-entypo-fontello' data-av_icon='\ue828' data-av_iconfont='entypo-fontello' title=\"Sa\u00fade Coletiva \" desc=\"Sa\u00fade Coletiva \" ><\/a><h3 class='iconbox_content_title '  itemprop=\"headline\" ><a href='https:\/\/www.odonto.ufmg.br\/teleodontologia\/saude-coletiva\/' title='Sa\u00fade Coletiva ' >Sa\u00fade Coletiva <\/a><\/h3><\/header><div class='iconbox_content_container '  itemprop=\"text\" ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><\/div>\n<div  class='flex_column av-5ocf9o-377aced95097c5ba7d182f9a1271cfb6 av_one_fourth  avia-builder-el-23  el_after_av_one_fourth  el_before_av_one_fourth  flex_column_div av-animated-generic bottom-to-top  column-top-margin'     ><article  class='iconbox iconbox_top av-kyu7qlao-d4ef2231d1d6c38c13da74a6a549b50d  avia-builder-el-24  avia-builder-el-no-sibling  main_color'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconbox_content\"><header class=\"entry-content-header\" aria-label=\"Icon: Pacientes com Necessidades Especiais\"><a href='https:\/\/www.odonto.ufmg.br\/teleodontologia\/pacientes-com-necessidades-especiais\/' title='Pacientes com Necessidades Especiais' aria-label='Pacientes com Necessidades Especiais'  class='iconbox_icon heading-color avia-iconfont avia-font-entypo-fontello' data-av_icon='\ue828' data-av_iconfont='entypo-fontello' title=\"Pacientes com Necessidades Especiais\" desc=\"Pacientes com Necessidades Especiais\" ><\/a><h3 class='iconbox_content_title '  itemprop=\"headline\" ><a href='https:\/\/www.odonto.ufmg.br\/teleodontologia\/pacientes-com-necessidades-especiais\/' title='Pacientes com Necessidades Especiais' >Pacientes com Necessidades Especiais<\/a><\/h3><\/header><div class='iconbox_content_container '  itemprop=\"text\" ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><\/div>\n<div  class='flex_column av-41a0cc-c1b4854685f711a3beeb8aa82c244590 av_one_fourth  avia-builder-el-25  el_after_av_one_fourth  el_before_av_one_fourth  flex_column_div av-animated-generic bottom-to-top  column-top-margin'     ><article  class='iconbox iconbox_top av-kyu7qyf3-9129d2bb66fab81a391459e008df4c39  avia-builder-el-26  avia-builder-el-no-sibling  main_color'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconbox_content\"><header class=\"entry-content-header\" aria-label=\"Icon: Radiologia e Imaginologia \"><a href='https:\/\/www.odonto.ufmg.br\/teleodontologia\/radiologia-e-imaginologia\/' title='Radiologia e Imaginologia ' aria-label='Radiologia e Imaginologia '  class='iconbox_icon heading-color avia-iconfont avia-font-entypo-fontello' data-av_icon='\ue828' data-av_iconfont='entypo-fontello' title=\"Radiologia e Imaginologia \" desc=\"Radiologia e Imaginologia \" ><\/a><h3 class='iconbox_content_title '  itemprop=\"headline\" ><a href='https:\/\/www.odonto.ufmg.br\/teleodontologia\/radiologia-e-imaginologia\/' title='Radiologia e Imaginologia ' >Radiologia e Imaginologia <\/a><\/h3><\/header><div class='iconbox_content_container '  itemprop=\"text\" ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><\/div>\n<div  class='flex_column av-1v0d5o-2b0e78aa48378ac686dc3c70dcb161a1 av_one_fourth  avia-builder-el-27  el_after_av_one_fourth  el_before_av_one_fourth  first flex_column_div av-animated-generic bottom-to-top  column-top-margin'     ><article  class='iconbox iconbox_top av-kyu7r6xq-8609f622c7a86e6e985577d517cb6267  avia-builder-el-28  avia-builder-el-no-sibling  main_color'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconbox_content\"><header class=\"entry-content-header\" aria-label=\"Icon: Ortodontia\"><a href='https:\/\/www.odonto.ufmg.br\/teleodontologia\/ortodontia\/' title='Ortodontia' aria-label='Ortodontia'  class='iconbox_icon heading-color avia-iconfont avia-font-entypo-fontello' data-av_icon='\ue828' data-av_iconfont='entypo-fontello' title=\"Ortodontia\" desc=\"Ortodontia\" ><\/a><h3 class='iconbox_content_title '  itemprop=\"headline\" ><a href='https:\/\/www.odonto.ufmg.br\/teleodontologia\/ortodontia\/' title='Ortodontia' >Ortodontia<\/a><\/h3><\/header><div class='iconbox_content_container '  itemprop=\"text\" ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><\/div>\n<div  class='flex_column av-2imf0c-fb4aa6073f4032415d3c63e08ae25646 av_one_fourth  avia-builder-el-29  el_after_av_one_fourth  avia-builder-el-last  flex_column_div av-animated-generic bottom-to-top  column-top-margin'     ><article  class='iconbox iconbox_top av-lesq9pd5-60eccf01d704ea5e1697400273fad513  avia-builder-el-30  avia-builder-el-no-sibling  main_color'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconbox_content\"><header class=\"entry-content-header\" aria-label=\"Icon: Urg\u00eancia\"><a href='https:\/\/www.odonto.ufmg.br\/teleodontologia\/urgencia\/' title='Urg\u00eancia' aria-label='Urg\u00eancia'  class='iconbox_icon heading-color avia-iconfont avia-font-entypo-fontello' data-av_icon='\ue828' data-av_iconfont='entypo-fontello' title=\"Urg\u00eancia\" desc=\"Urg\u00eancia\" ><\/a><h3 class='iconbox_content_title '  itemprop=\"headline\" ><a href='https:\/\/www.odonto.ufmg.br\/teleodontologia\/urgencia\/' title='Urg\u00eancia' >Urg\u00eancia<\/a><\/h3><\/header><div class='iconbox_content_container '  itemprop=\"text\" ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-1324","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Videoteca - Projeto Teleodontologia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.odonto.ufmg.br\/teleodontologia\/videoteca\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Videoteca - Projeto Teleodontologia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.odonto.ufmg.br\/teleodontologia\/videoteca\/\" \/>\n<meta property=\"og:site_name\" content=\"Projeto Teleodontologia\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-03T16:09:11+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"23 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/teleodontologia\\\/videoteca\\\/\",\"url\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/teleodontologia\\\/videoteca\\\/\",\"name\":\"Videoteca - Projeto Teleodontologia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/teleodontologia\\\/#website\"},\"datePublished\":\"2021-10-06T21:13:50+00:00\",\"dateModified\":\"2023-03-03T16:09:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/teleodontologia\\\/videoteca\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.odonto.ufmg.br\\\/teleodontologia\\\/videoteca\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/teleodontologia\\\/videoteca\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/teleodontologia\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Videoteca\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/teleodontologia\\\/#website\",\"url\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/teleodontologia\\\/\",\"name\":\"Projeto Teleodontologia\",\"description\":\"Biblioteca Virtual\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/teleodontologia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Videoteca - Projeto Teleodontologia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.odonto.ufmg.br\/teleodontologia\/videoteca\/","og_locale":"pt_BR","og_type":"article","og_title":"Videoteca - Projeto Teleodontologia","og_url":"https:\/\/www.odonto.ufmg.br\/teleodontologia\/videoteca\/","og_site_name":"Projeto Teleodontologia","article_modified_time":"2023-03-03T16:09:11+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"23 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.odonto.ufmg.br\/teleodontologia\/videoteca\/","url":"https:\/\/www.odonto.ufmg.br\/teleodontologia\/videoteca\/","name":"Videoteca - Projeto Teleodontologia","isPartOf":{"@id":"https:\/\/www.odonto.ufmg.br\/teleodontologia\/#website"},"datePublished":"2021-10-06T21:13:50+00:00","dateModified":"2023-03-03T16:09:11+00:00","breadcrumb":{"@id":"https:\/\/www.odonto.ufmg.br\/teleodontologia\/videoteca\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.odonto.ufmg.br\/teleodontologia\/videoteca\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.odonto.ufmg.br\/teleodontologia\/videoteca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.odonto.ufmg.br\/teleodontologia\/home\/"},{"@type":"ListItem","position":2,"name":"Videoteca"}]},{"@type":"WebSite","@id":"https:\/\/www.odonto.ufmg.br\/teleodontologia\/#website","url":"https:\/\/www.odonto.ufmg.br\/teleodontologia\/","name":"Projeto Teleodontologia","description":"Biblioteca Virtual","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.odonto.ufmg.br\/teleodontologia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"}]}},"_links":{"self":[{"href":"https:\/\/www.odonto.ufmg.br\/teleodontologia\/wp-json\/wp\/v2\/pages\/1324","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.odonto.ufmg.br\/teleodontologia\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.odonto.ufmg.br\/teleodontologia\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.odonto.ufmg.br\/teleodontologia\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.odonto.ufmg.br\/teleodontologia\/wp-json\/wp\/v2\/comments?post=1324"}],"version-history":[{"count":38,"href":"https:\/\/www.odonto.ufmg.br\/teleodontologia\/wp-json\/wp\/v2\/pages\/1324\/revisions"}],"predecessor-version":[{"id":2346,"href":"https:\/\/www.odonto.ufmg.br\/teleodontologia\/wp-json\/wp\/v2\/pages\/1324\/revisions\/2346"}],"wp:attachment":[{"href":"https:\/\/www.odonto.ufmg.br\/teleodontologia\/wp-json\/wp\/v2\/media?parent=1324"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}