{"id":3186,"date":"2021-10-27T15:14:22","date_gmt":"2021-10-27T18:14:22","guid":{"rendered":"https:\/\/www.odonto.ufmg.br\/sca\/?p=3186"},"modified":"2021-10-27T15:19:43","modified_gmt":"2021-10-27T18:19:43","slug":"divulgado-o-edital-10-2021","status":"publish","type":"post","link":"https:\/\/www.odonto.ufmg.br\/sca\/noticias\/divulgado-o-edital-10-2021\/","title":{"rendered":"Divulgado o Edital 10\/2021"},"content":{"rendered":"<p>A chefe do Departamento de Sa\u00fade Bucal da Crian\u00e7a e do Adolescente, da Faculdade de Odontologia da Universidade Federal de Minas Gerais, Profa. Miram Pimenta Parreira do Vale, faz saber que, de 22 de outubro a 1\u00ba de novembro (13horas), ser\u00e3o recebidos por email (odontopediatria.ufmg@gmail.com) inscri\u00e7\u00f5es de candidatos para o exame de sele\u00e7\u00e3o de 11 vagas (01 bolsista e 10 volunt\u00e1rios) para as disciplinas relacionadas ao Programa de Monitoria Volunt\u00e1ria de Gradua\u00e7\u00e3o do SCA.<\/p>\n<p>Per\u00edodo de inscri\u00e7\u00e3o: 22 de outubro a 1\u00ba de novembro (13horas).<\/p>\n<p>Para mais informa\u00e7\u00f5es, acesse o edital na \u00edntegra: <a href=\"https:\/\/www.odonto.ufmg.br\/sca\/wp-content\/uploads\/sites\/6\/2021\/10\/10-2021-Edital-de-Montoria-de-graduacao.pdf\">10-2021 Edital de Montoria de gradua\u00e7\u00e3o<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A chefe do Departamento de Sa\u00fade Bucal da Crian\u00e7a e do Adolescente, da Faculdade de Odontologia da Universidade Federal de Minas Gerais, Profa. Miram Pimenta Parreira do Vale, faz saber que, de 22 de outubro a 1\u00ba de novembro (13horas), ser\u00e3o recebidos por email (odontopediatria.ufmg@gmail.com) inscri\u00e7\u00f5es de candidatos para o exame de sele\u00e7\u00e3o de 11 [&hellip;]<\/p>\n","protected":false},"author":29,"featured_media":2676,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3186","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Divulgado o Edital 10\/2021 - Departamento de Sa\u00fade Bucal da Crian\u00e7a e do Adolescente<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.odonto.ufmg.br\/sca\/noticias\/divulgado-o-edital-10-2021\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Divulgado o Edital 10\/2021 - Departamento de Sa\u00fade Bucal da Crian\u00e7a e do Adolescente\" \/>\n<meta property=\"og:description\" content=\"A chefe do Departamento de Sa\u00fade Bucal da Crian\u00e7a e do Adolescente, da Faculdade de Odontologia da Universidade Federal de Minas Gerais, Profa. Miram Pimenta Parreira do Vale, faz saber que, de 22 de outubro a 1\u00ba de novembro (13horas), ser\u00e3o recebidos por email (odontopediatria.ufmg@gmail.com) inscri\u00e7\u00f5es de candidatos para o exame de sele\u00e7\u00e3o de 11 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.odonto.ufmg.br\/sca\/noticias\/divulgado-o-edital-10-2021\/\" \/>\n<meta property=\"og:site_name\" content=\"Departamento de Sa\u00fade Bucal da Crian\u00e7a e do Adolescente\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/faoufmg\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-27T18:14:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-27T18:19:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.odonto.ufmg.br\/sca\/wp-content\/uploads\/sites\/6\/2021\/02\/articulo-calendario-1-1024x683-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"raquel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"raquel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/sca\\\/noticias\\\/divulgado-o-edital-10-2021\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/sca\\\/noticias\\\/divulgado-o-edital-10-2021\\\/\"},\"author\":{\"name\":\"raquel\",\"@id\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/sca\\\/#\\\/schema\\\/person\\\/dcb886c1685c1fd050d36d61d761bd39\"},\"headline\":\"Divulgado o Edital 10\\\/2021\",\"datePublished\":\"2021-10-27T18:14:22+00:00\",\"dateModified\":\"2021-10-27T18:19:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/sca\\\/noticias\\\/divulgado-o-edital-10-2021\\\/\"},\"wordCount\":111,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/sca\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/sca\\\/noticias\\\/divulgado-o-edital-10-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/sca\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2021\\\/02\\\/articulo-calendario-1-1024x683-1.jpg\",\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/sca\\\/noticias\\\/divulgado-o-edital-10-2021\\\/\",\"url\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/sca\\\/noticias\\\/divulgado-o-edital-10-2021\\\/\",\"name\":\"Divulgado o Edital 10\\\/2021 - Departamento de Sa\u00fade Bucal da Crian\u00e7a e do Adolescente\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/sca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/sca\\\/noticias\\\/divulgado-o-edital-10-2021\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/sca\\\/noticias\\\/divulgado-o-edital-10-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/sca\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2021\\\/02\\\/articulo-calendario-1-1024x683-1.jpg\",\"datePublished\":\"2021-10-27T18:14:22+00:00\",\"dateModified\":\"2021-10-27T18:19:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/sca\\\/noticias\\\/divulgado-o-edital-10-2021\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.odonto.ufmg.br\\\/sca\\\/noticias\\\/divulgado-o-edital-10-2021\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/sca\\\/noticias\\\/divulgado-o-edital-10-2021\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/sca\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2021\\\/02\\\/articulo-calendario-1-1024x683-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/sca\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2021\\\/02\\\/articulo-calendario-1-1024x683-1.jpg\",\"width\":1024,\"height\":683},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/sca\\\/noticias\\\/divulgado-o-edital-10-2021\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/sca\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Divulgado o Edital 10\\\/2021\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/sca\\\/#website\",\"url\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/sca\\\/\",\"name\":\"Departamento de Sa\u00fade Bucal da Crian\u00e7a e do Adolescente\",\"description\":\"Faculdade de Odontologia - Universidade Federal de Minas Gerais\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/sca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/sca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/sca\\\/#organization\",\"name\":\"Departamento de Odontopediatria e Ortodontia\",\"url\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/sca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/sca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/sca\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2016\\\/02\\\/orto.svg\",\"contentUrl\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/sca\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2016\\\/02\\\/orto.svg\",\"width\":1,\"height\":1,\"caption\":\"Departamento de Odontopediatria e Ortodontia\"},\"image\":{\"@id\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/sca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/faoufmg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/sca\\\/#\\\/schema\\\/person\\\/dcb886c1685c1fd050d36d61d761bd39\",\"name\":\"raquel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4d7cd504af160bd29cb12213a21a574519997e1aea2d92b31b7ebd01c03286c9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4d7cd504af160bd29cb12213a21a574519997e1aea2d92b31b7ebd01c03286c9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4d7cd504af160bd29cb12213a21a574519997e1aea2d92b31b7ebd01c03286c9?s=96&d=mm&r=g\",\"caption\":\"raquel\"},\"url\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/sca\\\/author\\\/raquel\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Divulgado o Edital 10\/2021 - Departamento de Sa\u00fade Bucal da Crian\u00e7a e do Adolescente","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.odonto.ufmg.br\/sca\/noticias\/divulgado-o-edital-10-2021\/","og_locale":"pt_BR","og_type":"article","og_title":"Divulgado o Edital 10\/2021 - Departamento de Sa\u00fade Bucal da Crian\u00e7a e do Adolescente","og_description":"A chefe do Departamento de Sa\u00fade Bucal da Crian\u00e7a e do Adolescente, da Faculdade de Odontologia da Universidade Federal de Minas Gerais, Profa. Miram Pimenta Parreira do Vale, faz saber que, de 22 de outubro a 1\u00ba de novembro (13horas), ser\u00e3o recebidos por email (odontopediatria.ufmg@gmail.com) inscri\u00e7\u00f5es de candidatos para o exame de sele\u00e7\u00e3o de 11 [&hellip;]","og_url":"https:\/\/www.odonto.ufmg.br\/sca\/noticias\/divulgado-o-edital-10-2021\/","og_site_name":"Departamento de Sa\u00fade Bucal da Crian\u00e7a e do Adolescente","article_publisher":"https:\/\/www.facebook.com\/faoufmg","article_published_time":"2021-10-27T18:14:22+00:00","article_modified_time":"2021-10-27T18:19:43+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/www.odonto.ufmg.br\/sca\/wp-content\/uploads\/sites\/6\/2021\/02\/articulo-calendario-1-1024x683-1.jpg","type":"image\/jpeg"}],"author":"raquel","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"raquel","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.odonto.ufmg.br\/sca\/noticias\/divulgado-o-edital-10-2021\/#article","isPartOf":{"@id":"https:\/\/www.odonto.ufmg.br\/sca\/noticias\/divulgado-o-edital-10-2021\/"},"author":{"name":"raquel","@id":"https:\/\/www.odonto.ufmg.br\/sca\/#\/schema\/person\/dcb886c1685c1fd050d36d61d761bd39"},"headline":"Divulgado o Edital 10\/2021","datePublished":"2021-10-27T18:14:22+00:00","dateModified":"2021-10-27T18:19:43+00:00","mainEntityOfPage":{"@id":"https:\/\/www.odonto.ufmg.br\/sca\/noticias\/divulgado-o-edital-10-2021\/"},"wordCount":111,"commentCount":0,"publisher":{"@id":"https:\/\/www.odonto.ufmg.br\/sca\/#organization"},"image":{"@id":"https:\/\/www.odonto.ufmg.br\/sca\/noticias\/divulgado-o-edital-10-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/www.odonto.ufmg.br\/sca\/wp-content\/uploads\/sites\/6\/2021\/02\/articulo-calendario-1-1024x683-1.jpg","articleSection":["Not\u00edcias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.odonto.ufmg.br\/sca\/noticias\/divulgado-o-edital-10-2021\/","url":"https:\/\/www.odonto.ufmg.br\/sca\/noticias\/divulgado-o-edital-10-2021\/","name":"Divulgado o Edital 10\/2021 - Departamento de Sa\u00fade Bucal da Crian\u00e7a e do Adolescente","isPartOf":{"@id":"https:\/\/www.odonto.ufmg.br\/sca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.odonto.ufmg.br\/sca\/noticias\/divulgado-o-edital-10-2021\/#primaryimage"},"image":{"@id":"https:\/\/www.odonto.ufmg.br\/sca\/noticias\/divulgado-o-edital-10-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/www.odonto.ufmg.br\/sca\/wp-content\/uploads\/sites\/6\/2021\/02\/articulo-calendario-1-1024x683-1.jpg","datePublished":"2021-10-27T18:14:22+00:00","dateModified":"2021-10-27T18:19:43+00:00","breadcrumb":{"@id":"https:\/\/www.odonto.ufmg.br\/sca\/noticias\/divulgado-o-edital-10-2021\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.odonto.ufmg.br\/sca\/noticias\/divulgado-o-edital-10-2021\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.odonto.ufmg.br\/sca\/noticias\/divulgado-o-edital-10-2021\/#primaryimage","url":"https:\/\/www.odonto.ufmg.br\/sca\/wp-content\/uploads\/sites\/6\/2021\/02\/articulo-calendario-1-1024x683-1.jpg","contentUrl":"https:\/\/www.odonto.ufmg.br\/sca\/wp-content\/uploads\/sites\/6\/2021\/02\/articulo-calendario-1-1024x683-1.jpg","width":1024,"height":683},{"@type":"BreadcrumbList","@id":"https:\/\/www.odonto.ufmg.br\/sca\/noticias\/divulgado-o-edital-10-2021\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.odonto.ufmg.br\/sca\/inicio\/"},{"@type":"ListItem","position":2,"name":"Divulgado o Edital 10\/2021"}]},{"@type":"WebSite","@id":"https:\/\/www.odonto.ufmg.br\/sca\/#website","url":"https:\/\/www.odonto.ufmg.br\/sca\/","name":"Departamento de Sa\u00fade Bucal da Crian\u00e7a e do Adolescente","description":"Faculdade de Odontologia - Universidade Federal de Minas Gerais","publisher":{"@id":"https:\/\/www.odonto.ufmg.br\/sca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.odonto.ufmg.br\/sca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.odonto.ufmg.br\/sca\/#organization","name":"Departamento de Odontopediatria e Ortodontia","url":"https:\/\/www.odonto.ufmg.br\/sca\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.odonto.ufmg.br\/sca\/#\/schema\/logo\/image\/","url":"https:\/\/www.odonto.ufmg.br\/sca\/wp-content\/uploads\/sites\/6\/2016\/02\/orto.svg","contentUrl":"https:\/\/www.odonto.ufmg.br\/sca\/wp-content\/uploads\/sites\/6\/2016\/02\/orto.svg","width":1,"height":1,"caption":"Departamento de Odontopediatria e Ortodontia"},"image":{"@id":"https:\/\/www.odonto.ufmg.br\/sca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/faoufmg"]},{"@type":"Person","@id":"https:\/\/www.odonto.ufmg.br\/sca\/#\/schema\/person\/dcb886c1685c1fd050d36d61d761bd39","name":"raquel","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/4d7cd504af160bd29cb12213a21a574519997e1aea2d92b31b7ebd01c03286c9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4d7cd504af160bd29cb12213a21a574519997e1aea2d92b31b7ebd01c03286c9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4d7cd504af160bd29cb12213a21a574519997e1aea2d92b31b7ebd01c03286c9?s=96&d=mm&r=g","caption":"raquel"},"url":"https:\/\/www.odonto.ufmg.br\/sca\/author\/raquel\/"}]}},"_links":{"self":[{"href":"https:\/\/www.odonto.ufmg.br\/sca\/wp-json\/wp\/v2\/posts\/3186","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.odonto.ufmg.br\/sca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.odonto.ufmg.br\/sca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.odonto.ufmg.br\/sca\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/www.odonto.ufmg.br\/sca\/wp-json\/wp\/v2\/comments?post=3186"}],"version-history":[{"count":4,"href":"https:\/\/www.odonto.ufmg.br\/sca\/wp-json\/wp\/v2\/posts\/3186\/revisions"}],"predecessor-version":[{"id":3195,"href":"https:\/\/www.odonto.ufmg.br\/sca\/wp-json\/wp\/v2\/posts\/3186\/revisions\/3195"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.odonto.ufmg.br\/sca\/wp-json\/wp\/v2\/media\/2676"}],"wp:attachment":[{"href":"https:\/\/www.odonto.ufmg.br\/sca\/wp-json\/wp\/v2\/media?parent=3186"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.odonto.ufmg.br\/sca\/wp-json\/wp\/v2\/categories?post=3186"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.odonto.ufmg.br\/sca\/wp-json\/wp\/v2\/tags?post=3186"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}