﻿{"id":47,"count":28,"description":"","link":"https:\/\/www.odonto.ufmg.br\/sca\/category\/documentos\/editais\/","name":"Editais","slug":"editais","taxonomy":"category","parent":44,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arquivos Editais - Departamento de Sa\u00fade Bucal da Crian\u00e7a e do Adolescente<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.odonto.ufmg.br\/sca\/category\/documentos\/editais\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arquivos Editais - Departamento de Sa\u00fade Bucal da Crian\u00e7a e do Adolescente\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.odonto.ufmg.br\/sca\/category\/documentos\/editais\/\" \/>\n<meta property=\"og:site_name\" content=\"Departamento de Sa\u00fade Bucal da Crian\u00e7a e do Adolescente\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/sca\\\/category\\\/documentos\\\/editais\\\/\",\"url\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/sca\\\/category\\\/documentos\\\/editais\\\/\",\"name\":\"Arquivos Editais - Departamento de Sa\u00fade Bucal da Crian\u00e7a e do Adolescente\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/sca\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/sca\\\/category\\\/documentos\\\/editais\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/sca\\\/category\\\/documentos\\\/editais\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/sca\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Documentos\",\"item\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/sca\\\/category\\\/documentos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Editais\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/sca\\\/#website\",\"url\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/sca\\\/\",\"name\":\"Departamento de Sa\u00fade Bucal da Crian\u00e7a e do Adolescente\",\"description\":\"Faculdade de Odontologia - Universidade Federal de Minas Gerais\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/sca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/sca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/sca\\\/#organization\",\"name\":\"Departamento de Odontopediatria e Ortodontia\",\"url\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/sca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/sca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/sca\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2016\\\/02\\\/orto.svg\",\"contentUrl\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/sca\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2016\\\/02\\\/orto.svg\",\"width\":1,\"height\":1,\"caption\":\"Departamento de Odontopediatria e Ortodontia\"},\"image\":{\"@id\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/sca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/faoufmg\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arquivos Editais - Departamento de Sa\u00fade Bucal da Crian\u00e7a e do Adolescente","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.odonto.ufmg.br\/sca\/category\/documentos\/editais\/","og_locale":"pt_BR","og_type":"article","og_title":"Arquivos Editais - Departamento de Sa\u00fade Bucal da Crian\u00e7a e do Adolescente","og_url":"https:\/\/www.odonto.ufmg.br\/sca\/category\/documentos\/editais\/","og_site_name":"Departamento de Sa\u00fade Bucal da Crian\u00e7a e do Adolescente","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.odonto.ufmg.br\/sca\/category\/documentos\/editais\/","url":"https:\/\/www.odonto.ufmg.br\/sca\/category\/documentos\/editais\/","name":"Arquivos Editais - Departamento de Sa\u00fade Bucal da Crian\u00e7a e do Adolescente","isPartOf":{"@id":"https:\/\/www.odonto.ufmg.br\/sca\/#website"},"breadcrumb":{"@id":"https:\/\/www.odonto.ufmg.br\/sca\/category\/documentos\/editais\/#breadcrumb"},"inLanguage":"pt-BR"},{"@type":"BreadcrumbList","@id":"https:\/\/www.odonto.ufmg.br\/sca\/category\/documentos\/editais\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.odonto.ufmg.br\/sca\/inicio\/"},{"@type":"ListItem","position":2,"name":"Documentos","item":"https:\/\/www.odonto.ufmg.br\/sca\/category\/documentos\/"},{"@type":"ListItem","position":3,"name":"Editais"}]},{"@type":"WebSite","@id":"https:\/\/www.odonto.ufmg.br\/sca\/#website","url":"https:\/\/www.odonto.ufmg.br\/sca\/","name":"Departamento de Sa\u00fade Bucal da Crian\u00e7a e do Adolescente","description":"Faculdade de Odontologia - Universidade Federal de Minas Gerais","publisher":{"@id":"https:\/\/www.odonto.ufmg.br\/sca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.odonto.ufmg.br\/sca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.odonto.ufmg.br\/sca\/#organization","name":"Departamento de Odontopediatria e Ortodontia","url":"https:\/\/www.odonto.ufmg.br\/sca\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.odonto.ufmg.br\/sca\/#\/schema\/logo\/image\/","url":"https:\/\/www.odonto.ufmg.br\/sca\/wp-content\/uploads\/sites\/6\/2016\/02\/orto.svg","contentUrl":"https:\/\/www.odonto.ufmg.br\/sca\/wp-content\/uploads\/sites\/6\/2016\/02\/orto.svg","width":1,"height":1,"caption":"Departamento de Odontopediatria e Ortodontia"},"image":{"@id":"https:\/\/www.odonto.ufmg.br\/sca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/faoufmg"]}]}},"_links":{"self":[{"href":"https:\/\/www.odonto.ufmg.br\/sca\/wp-json\/wp\/v2\/categories\/47","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.odonto.ufmg.br\/sca\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.odonto.ufmg.br\/sca\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/www.odonto.ufmg.br\/sca\/wp-json\/wp\/v2\/categories\/44"}],"wp:post_type":[{"href":"https:\/\/www.odonto.ufmg.br\/sca\/wp-json\/wp\/v2\/posts?categories=47"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}