{"id":141,"date":"2018-03-26T13:10:35","date_gmt":"2018-03-26T16:10:35","guid":{"rendered":"https:\/\/www.odonto.ufmg.br\/osp\/?p=141"},"modified":"2018-08-09T12:14:47","modified_gmt":"2018-08-09T15:14:47","slug":"bem-vindos-ao-novo-site-do-osp","status":"publish","type":"post","link":"https:\/\/www.odonto.ufmg.br\/osp\/geral\/bem-vindos-ao-novo-site-do-osp\/","title":{"rendered":"Bem-vindos ao site do OSP"},"content":{"rendered":"<p>Bem-vindos ao site do OSP.\u00a0Navegando pelo menu acima, voc\u00ea\u00a0encontra todas as not\u00edcias, informa\u00e7\u00f5es e documentos relacionados ao departamento. Caso ocorram problemas, entre em contato conosco atrav\u00e9s do\u00a0<a href=\"https:\/\/www.odonto.ufmg.br\/osp\/contatos\/\">formul\u00e1rio<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bem-vindos ao site do OSP.\u00a0Navegando pelo menu acima, voc\u00ea\u00a0encontra todas as not\u00edcias, informa\u00e7\u00f5es e documentos relacionados ao departamento. Caso ocorram problemas, entre em contato conosco atrav\u00e9s do\u00a0formul\u00e1rio.<\/p>\n","protected":false},"author":5,"featured_media":142,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-141","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bem-vindos ao site do OSP - Departamento de Odontologia Social e Preventiva<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.odonto.ufmg.br\/osp\/geral\/bem-vindos-ao-novo-site-do-osp\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bem-vindos ao site do OSP - Departamento de Odontologia Social e Preventiva\" \/>\n<meta property=\"og:description\" content=\"Bem-vindos ao site do OSP.\u00a0Navegando pelo menu acima, voc\u00ea\u00a0encontra todas as not\u00edcias, informa\u00e7\u00f5es e documentos relacionados ao departamento. Caso ocorram problemas, entre em contato conosco atrav\u00e9s do\u00a0formul\u00e1rio.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.odonto.ufmg.br\/osp\/geral\/bem-vindos-ao-novo-site-do-osp\/\" \/>\n<meta property=\"og:site_name\" content=\"Departamento de Odontologia Social e Preventiva\" \/>\n<meta property=\"article:published_time\" content=\"2018-03-26T16:10:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-08-09T15:14:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.odonto.ufmg.br\/osp\/wp-content\/uploads\/sites\/20\/2018\/02\/DSCN0634.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1536\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cristiano\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"cristiano\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/osp\\\/geral\\\/bem-vindos-ao-novo-site-do-osp\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/osp\\\/geral\\\/bem-vindos-ao-novo-site-do-osp\\\/\"},\"author\":{\"name\":\"cristiano\",\"@id\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/osp\\\/#\\\/schema\\\/person\\\/25c8dccfb2b8a933d4c9cacb1f1bf0db\"},\"headline\":\"Bem-vindos ao site do OSP\",\"datePublished\":\"2018-03-26T16:10:35+00:00\",\"dateModified\":\"2018-08-09T15:14:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/osp\\\/geral\\\/bem-vindos-ao-novo-site-do-osp\\\/\"},\"wordCount\":39,\"image\":{\"@id\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/osp\\\/geral\\\/bem-vindos-ao-novo-site-do-osp\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/osp\\\/wp-content\\\/uploads\\\/sites\\\/20\\\/2018\\\/02\\\/DSCN0634.jpg\",\"articleSection\":[\"Geral\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/osp\\\/geral\\\/bem-vindos-ao-novo-site-do-osp\\\/\",\"url\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/osp\\\/geral\\\/bem-vindos-ao-novo-site-do-osp\\\/\",\"name\":\"Bem-vindos ao site do OSP - Departamento de Odontologia Social e Preventiva\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/osp\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/osp\\\/geral\\\/bem-vindos-ao-novo-site-do-osp\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/osp\\\/geral\\\/bem-vindos-ao-novo-site-do-osp\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/osp\\\/wp-content\\\/uploads\\\/sites\\\/20\\\/2018\\\/02\\\/DSCN0634.jpg\",\"datePublished\":\"2018-03-26T16:10:35+00:00\",\"dateModified\":\"2018-08-09T15:14:47+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/osp\\\/#\\\/schema\\\/person\\\/25c8dccfb2b8a933d4c9cacb1f1bf0db\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/osp\\\/geral\\\/bem-vindos-ao-novo-site-do-osp\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.odonto.ufmg.br\\\/osp\\\/geral\\\/bem-vindos-ao-novo-site-do-osp\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/osp\\\/geral\\\/bem-vindos-ao-novo-site-do-osp\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/osp\\\/wp-content\\\/uploads\\\/sites\\\/20\\\/2018\\\/02\\\/DSCN0634.jpg\",\"contentUrl\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/osp\\\/wp-content\\\/uploads\\\/sites\\\/20\\\/2018\\\/02\\\/DSCN0634.jpg\",\"width\":2048,\"height\":1536},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/osp\\\/geral\\\/bem-vindos-ao-novo-site-do-osp\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/osp\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bem-vindos ao site do OSP\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/osp\\\/#website\",\"url\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/osp\\\/\",\"name\":\"Departamento de Odontologia Social e Preventiva\",\"description\":\"S\u00f3 mais um site Faculdade de Odontologia Universidade Federal de Minas Gerais\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/osp\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/osp\\\/#\\\/schema\\\/person\\\/25c8dccfb2b8a933d4c9cacb1f1bf0db\",\"name\":\"cristiano\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ca61e4454966479a762b9f7682317c841b3f6d64d4eaeb9737c72573dfea596?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ca61e4454966479a762b9f7682317c841b3f6d64d4eaeb9737c72573dfea596?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ca61e4454966479a762b9f7682317c841b3f6d64d4eaeb9737c72573dfea596?s=96&d=mm&r=g\",\"caption\":\"cristiano\"},\"url\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/osp\\\/author\\\/cristiano\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bem-vindos ao site do OSP - Departamento de Odontologia Social e Preventiva","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.odonto.ufmg.br\/osp\/geral\/bem-vindos-ao-novo-site-do-osp\/","og_locale":"pt_BR","og_type":"article","og_title":"Bem-vindos ao site do OSP - Departamento de Odontologia Social e Preventiva","og_description":"Bem-vindos ao site do OSP.\u00a0Navegando pelo menu acima, voc\u00ea\u00a0encontra todas as not\u00edcias, informa\u00e7\u00f5es e documentos relacionados ao departamento. Caso ocorram problemas, entre em contato conosco atrav\u00e9s do\u00a0formul\u00e1rio.","og_url":"https:\/\/www.odonto.ufmg.br\/osp\/geral\/bem-vindos-ao-novo-site-do-osp\/","og_site_name":"Departamento de Odontologia Social e Preventiva","article_published_time":"2018-03-26T16:10:35+00:00","article_modified_time":"2018-08-09T15:14:47+00:00","og_image":[{"width":2048,"height":1536,"url":"https:\/\/www.odonto.ufmg.br\/osp\/wp-content\/uploads\/sites\/20\/2018\/02\/DSCN0634.jpg","type":"image\/jpeg"}],"author":"cristiano","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"cristiano"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.odonto.ufmg.br\/osp\/geral\/bem-vindos-ao-novo-site-do-osp\/#article","isPartOf":{"@id":"https:\/\/www.odonto.ufmg.br\/osp\/geral\/bem-vindos-ao-novo-site-do-osp\/"},"author":{"name":"cristiano","@id":"https:\/\/www.odonto.ufmg.br\/osp\/#\/schema\/person\/25c8dccfb2b8a933d4c9cacb1f1bf0db"},"headline":"Bem-vindos ao site do OSP","datePublished":"2018-03-26T16:10:35+00:00","dateModified":"2018-08-09T15:14:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.odonto.ufmg.br\/osp\/geral\/bem-vindos-ao-novo-site-do-osp\/"},"wordCount":39,"image":{"@id":"https:\/\/www.odonto.ufmg.br\/osp\/geral\/bem-vindos-ao-novo-site-do-osp\/#primaryimage"},"thumbnailUrl":"https:\/\/www.odonto.ufmg.br\/osp\/wp-content\/uploads\/sites\/20\/2018\/02\/DSCN0634.jpg","articleSection":["Geral"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.odonto.ufmg.br\/osp\/geral\/bem-vindos-ao-novo-site-do-osp\/","url":"https:\/\/www.odonto.ufmg.br\/osp\/geral\/bem-vindos-ao-novo-site-do-osp\/","name":"Bem-vindos ao site do OSP - Departamento de Odontologia Social e Preventiva","isPartOf":{"@id":"https:\/\/www.odonto.ufmg.br\/osp\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.odonto.ufmg.br\/osp\/geral\/bem-vindos-ao-novo-site-do-osp\/#primaryimage"},"image":{"@id":"https:\/\/www.odonto.ufmg.br\/osp\/geral\/bem-vindos-ao-novo-site-do-osp\/#primaryimage"},"thumbnailUrl":"https:\/\/www.odonto.ufmg.br\/osp\/wp-content\/uploads\/sites\/20\/2018\/02\/DSCN0634.jpg","datePublished":"2018-03-26T16:10:35+00:00","dateModified":"2018-08-09T15:14:47+00:00","author":{"@id":"https:\/\/www.odonto.ufmg.br\/osp\/#\/schema\/person\/25c8dccfb2b8a933d4c9cacb1f1bf0db"},"breadcrumb":{"@id":"https:\/\/www.odonto.ufmg.br\/osp\/geral\/bem-vindos-ao-novo-site-do-osp\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.odonto.ufmg.br\/osp\/geral\/bem-vindos-ao-novo-site-do-osp\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.odonto.ufmg.br\/osp\/geral\/bem-vindos-ao-novo-site-do-osp\/#primaryimage","url":"https:\/\/www.odonto.ufmg.br\/osp\/wp-content\/uploads\/sites\/20\/2018\/02\/DSCN0634.jpg","contentUrl":"https:\/\/www.odonto.ufmg.br\/osp\/wp-content\/uploads\/sites\/20\/2018\/02\/DSCN0634.jpg","width":2048,"height":1536},{"@type":"BreadcrumbList","@id":"https:\/\/www.odonto.ufmg.br\/osp\/geral\/bem-vindos-ao-novo-site-do-osp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.odonto.ufmg.br\/osp\/"},{"@type":"ListItem","position":2,"name":"Bem-vindos ao site do OSP"}]},{"@type":"WebSite","@id":"https:\/\/www.odonto.ufmg.br\/osp\/#website","url":"https:\/\/www.odonto.ufmg.br\/osp\/","name":"Departamento de Odontologia Social e Preventiva","description":"S\u00f3 mais um site Faculdade de Odontologia Universidade Federal de Minas Gerais","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.odonto.ufmg.br\/osp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.odonto.ufmg.br\/osp\/#\/schema\/person\/25c8dccfb2b8a933d4c9cacb1f1bf0db","name":"cristiano","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/3ca61e4454966479a762b9f7682317c841b3f6d64d4eaeb9737c72573dfea596?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3ca61e4454966479a762b9f7682317c841b3f6d64d4eaeb9737c72573dfea596?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3ca61e4454966479a762b9f7682317c841b3f6d64d4eaeb9737c72573dfea596?s=96&d=mm&r=g","caption":"cristiano"},"url":"https:\/\/www.odonto.ufmg.br\/osp\/author\/cristiano\/"}]}},"_links":{"self":[{"href":"https:\/\/www.odonto.ufmg.br\/osp\/wp-json\/wp\/v2\/posts\/141","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.odonto.ufmg.br\/osp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.odonto.ufmg.br\/osp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.odonto.ufmg.br\/osp\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.odonto.ufmg.br\/osp\/wp-json\/wp\/v2\/comments?post=141"}],"version-history":[{"count":5,"href":"https:\/\/www.odonto.ufmg.br\/osp\/wp-json\/wp\/v2\/posts\/141\/revisions"}],"predecessor-version":[{"id":503,"href":"https:\/\/www.odonto.ufmg.br\/osp\/wp-json\/wp\/v2\/posts\/141\/revisions\/503"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.odonto.ufmg.br\/osp\/wp-json\/wp\/v2\/media\/142"}],"wp:attachment":[{"href":"https:\/\/www.odonto.ufmg.br\/osp\/wp-json\/wp\/v2\/media?parent=141"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.odonto.ufmg.br\/osp\/wp-json\/wp\/v2\/categories?post=141"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.odonto.ufmg.br\/osp\/wp-json\/wp\/v2\/tags?post=141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}