{"id":3728,"date":"2016-09-15T09:16:37","date_gmt":"2016-09-15T12:16:37","guid":{"rendered":"https:\/\/www.odonto.ufmg.br\/odr\/?post_type=portfolio&#038;p=3728"},"modified":"2016-09-16T10:40:23","modified_gmt":"2016-09-16T13:40:23","slug":"tratamento-endodontico-de-molares","status":"publish","type":"portfolio","link":"https:\/\/www.odonto.ufmg.br\/odr\/disciplinas\/tratamento-endodontico-de-molares\/","title":{"rendered":"Tratamento Endod\u00f4ntico de Molares"},"content":{"rendered":"\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_section-2705223b78ae2265e67c01c283989336\">\n.avia-section.av-av_section-2705223b78ae2265e67c01c283989336 .av-parallax .av-parallax-inner{\nbackground-repeat:no-repeat;\nbackground-image:url(https:\/\/www.odonto.ufmg.br\/odr\/wp-content\/uploads\/sites\/7\/2016\/09\/Root-Canal.jpg);\nbackground-position:50% 50%;\nbackground-attachment:scroll;\n}\n.avia-section.av-av_section-2705223b78ae2265e67c01c283989336 .av-section-color-overlay{\nopacity:0.5;\nbackground-color:#000000;\n}\n<\/style>\n<div id='av_section_1'  class='avia-section av-av_section-2705223b78ae2265e67c01c283989336 main_color avia-section-default avia-no-shadow  avia-builder-el-0  el_before_av_layout_row  avia-builder-el-first  avia-full-stretch av-parallax-section avia-bg-style-parallax av-section-color-overlay-active av-minimum-height av-minimum-height-50 av-height-50  container_wrap fullsize'  data-section-bg-repeat='stretch' data-av_minimum_height_pc='50' data-av_min_height_opt='50'><div class='av-parallax' data-avia-parallax-ratio='0.3' ><div class='av-parallax-inner main_color avia-full-stretch'><\/div><\/div><div class=\"av-section-color-overlay-wrap\"><div class=\"av-section-color-overlay\"><\/div><a href='#next-section' title='' class='scroll-down-link  avia-svg-icon avia-font-svg_entypo-fontello' data-av_svg_icon='down-open-mini' data-av_iconset='svg_entypo-fontello'><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15\" height=\"32\" viewBox=\"0 0 15 32\" preserveAspectRatio=\"xMidYMid meet\" aria-labelledby='av-svg-title-1' aria-describedby='av-svg-desc-1' role=\"graphics-symbol\" aria-hidden=\"true\">\n<title id='av-svg-title-1'>Scroll to next section<\/title>\n<desc id='av-svg-desc-1'>Scroll to next section<\/desc>\n<path d=\"M12.96 12.16q0.704-0.832 1.536 0 0.832 0.704 0 1.536l-6.272 6.144q-0.704 0.704-1.536 0l-6.272-6.144q-0.832-0.832 0-1.536 0.768-0.768 1.6 0l5.44 4.992z\"><\/path>\n<\/svg><\/a><div class='container av-section-cont-open' ><main  role=\"main\" itemprop=\"mainContentOfPage\"  class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-3728'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_full-d71a51a707c4656b37c9afbbd6138215\">\n.flex_column.av-av_one_full-d71a51a707c4656b37c9afbbd6138215{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_full-d71a51a707c4656b37c9afbbd6138215 av_one_full  avia-builder-el-1  avia-builder-el-no-sibling  first flex_column_div av-animated-generic bottom-to-top av-zero-column-padding  '     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_heading-8951b8f68c5a835e2852dd45fc146e13\">\n#top .av-special-heading.av-av_heading-8951b8f68c5a835e2852dd45fc146e13{\npadding-bottom:0;\ncolor:#ffffff;\nfont-size:40px;\n}\nbody .av-special-heading.av-av_heading-8951b8f68c5a835e2852dd45fc146e13 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n#top #wrap_all .av-special-heading.av-av_heading-8951b8f68c5a835e2852dd45fc146e13 .av-special-heading-tag{\nfont-size:40px;\n}\n.av-special-heading.av-av_heading-8951b8f68c5a835e2852dd45fc146e13 .special-heading-inner-border{\nborder-color:#ffffff;\n}\n.av-special-heading.av-av_heading-8951b8f68c5a835e2852dd45fc146e13 .av-subheading{\nfont-size:40px;\n}\n\n@media only screen and (min-width: 480px) and (max-width: 767px){ \n#top #wrap_all .av-special-heading.av-av_heading-8951b8f68c5a835e2852dd45fc146e13 .av-special-heading-tag{\nfont-size:0.8em;\n}\n}\n\n@media only screen and (max-width: 479px){ \n#top #wrap_all .av-special-heading.av-av_heading-8951b8f68c5a835e2852dd45fc146e13 .av-special-heading-tag{\nfont-size:0.8em;\n}\n}\n<\/style>\n<div  class='av-special-heading av-av_heading-8951b8f68c5a835e2852dd45fc146e13 av-special-heading-h3 custom-color-heading blockquote modern-quote modern-centered  avia-builder-el-2  el_before_av_hr  avia-builder-el-first  av-inherit-size'><h3 class='av-special-heading-tag '  itemprop=\"headline\"  >Tratamento Endod\u00f4ntico de Molares<\/h3><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_hr-c282f4cd9bd3f3c176a54b23e2e441a5\">\n#top .hr.av-av_hr-c282f4cd9bd3f3c176a54b23e2e441a5{\nmargin-top:5px;\nmargin-bottom:35px;\n}\n.hr.av-av_hr-c282f4cd9bd3f3c176a54b23e2e441a5 .hr-inner{\nwidth:50px;\nborder-color:#efbb20;\n}\n<\/style>\n<div  class='hr av-av_hr-c282f4cd9bd3f3c176a54b23e2e441a5 hr-custom  avia-builder-el-3  el_after_av_heading  avia-builder-el-last  hr-center hr-icon-no'><span class='hr-inner inner-border-av-border-fat'><span class=\"hr-inner-style\"><\/span><\/span><\/div><\/p><\/div>\n\n<\/div><\/div><\/main><!-- close content main element --><\/div><\/div><\/div><div id='av-layout-grid-1'  class='av-layout-grid-container av-av_layout_row-d33986b140bd8e03ac046ce4e36b6832 entry-content-wrapper main_color av-flex-cells  avia-builder-el-4  el_after_av_section  avia-builder-el-last  grid-row-not-first  container_wrap fullsize'  >\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_cell_one_full-e00c26a1a439f0f470fd6e7e74fa6685\">\n.flex_cell.av-av_cell_one_full-e00c26a1a439f0f470fd6e7e74fa6685{\nvertical-align:middle;\nheight:400px;\nmin-height:400px;\n}\n.responsive #top #wrap_all .flex_cell.av-av_cell_one_full-e00c26a1a439f0f470fd6e7e74fa6685{\npadding:60px 60px 60px 60px !important;\n}\n<\/style>\n<div class='flex_cell av-av_cell_one_full-e00c26a1a439f0f470fd6e7e74fa6685 av-gridrow-cell av_one_full no_margin  avia-builder-el-5  avia-builder-el-no-sibling  content-align-middle'  ><div class='flex_cell_inner'><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_full-d71a51a707c4656b37c9afbbd6138215\">\n.flex_column.av-av_one_full-d71a51a707c4656b37c9afbbd6138215{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_full-d71a51a707c4656b37c9afbbd6138215 av_one_full  avia-builder-el-6  el_before_av_one_full  avia-builder-el-first  first flex_column_div av-animated-generic bottom-to-top av-zero-column-padding  '     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_heading-c7ba9dc5db7c4e479e170540dcc1013f\">\n#top .av-special-heading.av-av_heading-c7ba9dc5db7c4e479e170540dcc1013f{\npadding-bottom:0;\n}\nbody .av-special-heading.av-av_heading-c7ba9dc5db7c4e479e170540dcc1013f .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-av_heading-c7ba9dc5db7c4e479e170540dcc1013f .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-av_heading-c7ba9dc5db7c4e479e170540dcc1013f av-special-heading-h3 blockquote modern-quote  avia-builder-el-7  el_before_av_hr  avia-builder-el-first '><h3 class='av-special-heading-tag '  itemprop=\"headline\"  >Objetivo Geral<\/h3><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_hr-3e128d09911abf776949821b39a02bfe\">\n#top .hr.av-av_hr-3e128d09911abf776949821b39a02bfe{\nmargin-top:10px;\nmargin-bottom:10px;\n}\n.hr.av-av_hr-3e128d09911abf776949821b39a02bfe .hr-inner{\nwidth:50px;\nborder-color:#efbb20;\n}\n<\/style>\n<div  class='hr av-av_hr-3e128d09911abf776949821b39a02bfe hr-custom  avia-builder-el-8  el_after_av_heading  el_before_av_textblock  hr-left hr-icon-no'><span class='hr-inner inner-border-av-border-fat'><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<section  class='av_textblock_section av-av_textblock-0366cc7376be6c9e82a3e9cc8987b64f '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p>Desenvolvimento de habilidades para a realiza\u00e7\u00e3o do tratamento endo\u00f4ntico de maior complexidade.<\/p>\n<\/div><\/section><\/p><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_full-d71a51a707c4656b37c9afbbd6138215\">\n.flex_column.av-av_one_full-d71a51a707c4656b37c9afbbd6138215{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_full-d71a51a707c4656b37c9afbbd6138215 av_one_full  avia-builder-el-10  el_after_av_one_full  el_before_av_one_full  first flex_column_div av-animated-generic bottom-to-top av-zero-column-padding  column-top-margin'     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_heading-effd6a08769ec93046a81ac9e6a6a0c1\">\n#top .av-special-heading.av-av_heading-effd6a08769ec93046a81ac9e6a6a0c1{\npadding-bottom:0;\n}\nbody .av-special-heading.av-av_heading-effd6a08769ec93046a81ac9e6a6a0c1 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-av_heading-effd6a08769ec93046a81ac9e6a6a0c1 .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-av_heading-effd6a08769ec93046a81ac9e6a6a0c1 av-special-heading-h3 blockquote modern-quote  avia-builder-el-11  el_before_av_hr  avia-builder-el-first '><h3 class='av-special-heading-tag '  itemprop=\"headline\"  >Objetivos Espec\u00edficos<\/h3><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_hr-3e128d09911abf776949821b39a02bfe\">\n#top .hr.av-av_hr-3e128d09911abf776949821b39a02bfe{\nmargin-top:10px;\nmargin-bottom:10px;\n}\n.hr.av-av_hr-3e128d09911abf776949821b39a02bfe .hr-inner{\nwidth:50px;\nborder-color:#efbb20;\n}\n<\/style>\n<div  class='hr av-av_hr-3e128d09911abf776949821b39a02bfe hr-custom  avia-builder-el-12  el_after_av_heading  el_before_av_textblock  hr-left hr-icon-no'><span class='hr-inner inner-border-av-border-fat'><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<section  class='av_textblock_section av-av_textblock-0366cc7376be6c9e82a3e9cc8987b64f '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><ul>\n<li>Conhecer os recursos e t\u00e9cnicas para a realiza\u00e7\u00e3o do tratamento endod\u00f4ntico de molares, dentes com rizog\u00eanese incompleta e\/ou dentes traumatizados.<\/li>\n<li>\u00a0Conhecer as condutas frente aos acidentes e complica\u00e7\u00f5es do tratamento endod\u00f4ntico e sobre o emprego do MTA.<\/li>\n<\/ul>\n<\/div><\/section><\/p><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_full-d71a51a707c4656b37c9afbbd6138215\">\n.flex_column.av-av_one_full-d71a51a707c4656b37c9afbbd6138215{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_full-d71a51a707c4656b37c9afbbd6138215 av_one_full  avia-builder-el-14  el_after_av_one_full  el_before_av_one_full  first flex_column_div av-animated-generic bottom-to-top av-zero-column-padding  column-top-margin'     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_heading-863998279fddca80855a9192a7018520\">\n#top .av-special-heading.av-av_heading-863998279fddca80855a9192a7018520{\npadding-bottom:0;\n}\nbody .av-special-heading.av-av_heading-863998279fddca80855a9192a7018520 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-av_heading-863998279fddca80855a9192a7018520 .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-av_heading-863998279fddca80855a9192a7018520 av-special-heading-h3 blockquote modern-quote  avia-builder-el-15  el_before_av_hr  avia-builder-el-first '><h3 class='av-special-heading-tag '  itemprop=\"headline\"  >Ementa<\/h3><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_hr-3e128d09911abf776949821b39a02bfe\">\n#top .hr.av-av_hr-3e128d09911abf776949821b39a02bfe{\nmargin-top:10px;\nmargin-bottom:10px;\n}\n.hr.av-av_hr-3e128d09911abf776949821b39a02bfe .hr-inner{\nwidth:50px;\nborder-color:#efbb20;\n}\n<\/style>\n<div  class='hr av-av_hr-3e128d09911abf776949821b39a02bfe hr-custom  avia-builder-el-16  el_after_av_heading  el_before_av_textblock  hr-left hr-icon-no'><span class='hr-inner inner-border-av-border-fat'><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<section  class='av_textblock_section av-av_textblock-0366cc7376be6c9e82a3e9cc8987b64f '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p>T\u00e9cnica e recursos para o tratamento endod\u00f4ntico radical em dentes tri-radiculados e em dentes permanentes jovens. Conduta frente aos traumatismos dent\u00e1rios e aos acidentes e complica\u00e7\u00f5es endod\u00f4nticas e o emprego do cimento MTA.<\/p>\n<\/div><\/section><\/p><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_full-d71a51a707c4656b37c9afbbd6138215\">\n.flex_column.av-av_one_full-d71a51a707c4656b37c9afbbd6138215{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_full-d71a51a707c4656b37c9afbbd6138215 av_one_full  avia-builder-el-18  el_after_av_one_full  el_before_av_one_full  first flex_column_div av-animated-generic bottom-to-top av-zero-column-padding  column-top-margin'     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_heading-3ba08d5caab19681a5019580dbd617bc\">\n#top .av-special-heading.av-av_heading-3ba08d5caab19681a5019580dbd617bc{\npadding-bottom:0;\n}\nbody .av-special-heading.av-av_heading-3ba08d5caab19681a5019580dbd617bc .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-av_heading-3ba08d5caab19681a5019580dbd617bc .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-av_heading-3ba08d5caab19681a5019580dbd617bc av-special-heading-h3 blockquote modern-quote  avia-builder-el-19  el_before_av_hr  avia-builder-el-first '><h3 class='av-special-heading-tag '  itemprop=\"headline\"  > Conte\u00fado<\/h3><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_hr-3e128d09911abf776949821b39a02bfe\">\n#top .hr.av-av_hr-3e128d09911abf776949821b39a02bfe{\nmargin-top:10px;\nmargin-bottom:10px;\n}\n.hr.av-av_hr-3e128d09911abf776949821b39a02bfe .hr-inner{\nwidth:50px;\nborder-color:#efbb20;\n}\n<\/style>\n<div  class='hr av-av_hr-3e128d09911abf776949821b39a02bfe hr-custom  avia-builder-el-20  el_after_av_heading  el_before_av_textblock  hr-left hr-icon-no'><span class='hr-inner inner-border-av-border-fat'><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_textblock-8e5bdedebac81bcd937ed355ccd26d60\">\n#top .av_textblock_section.av-av_textblock-8e5bdedebac81bcd937ed355ccd26d60 .avia_textblock{\ncolor:#000000;\n}\n<\/style>\n<section  class='av_textblock_section av-av_textblock-8e5bdedebac81bcd937ed355ccd26d60 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock av_inherit_color'  itemprop=\"text\" ><ul>\n<li>Limpeza e Formata\u00e7\/ao do SCR em Molares utilizando os instrumentos rotat\u00f3rios de n\u00edqueltit\u00e2nico (NiTi).<\/li>\n<li>Etiopatogenia das altera\u00e7\u00f5es periapicais.<\/li>\n<li>\u00a0Tratamento Endod\u00f4ntico de dentes permanentes jovens e\/ou traumatizados.<\/li>\n<li>Acidentes e complica\u00e7\u00f5es em Endodontia e o uso de MTA.<\/li>\n<li>\u00a0Conte\u00fado dos estudos dirigidos ser\u00e3o temas atuais<\/li>\n<\/ul>\n<\/div><\/section><\/p><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_full-d71a51a707c4656b37c9afbbd6138215\">\n.flex_column.av-av_one_full-d71a51a707c4656b37c9afbbd6138215{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_full-d71a51a707c4656b37c9afbbd6138215 av_one_full  avia-builder-el-22  el_after_av_one_full  el_before_av_one_full  first flex_column_div av-animated-generic bottom-to-top av-zero-column-padding  column-top-margin'     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_heading-58850a6270a0c08df59d226784690b8b\">\n#top .av-special-heading.av-av_heading-58850a6270a0c08df59d226784690b8b{\npadding-bottom:0;\n}\nbody .av-special-heading.av-av_heading-58850a6270a0c08df59d226784690b8b .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-av_heading-58850a6270a0c08df59d226784690b8b .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-av_heading-58850a6270a0c08df59d226784690b8b av-special-heading-h3 blockquote modern-quote  avia-builder-el-23  el_before_av_hr  avia-builder-el-first '><h3 class='av-special-heading-tag '  itemprop=\"headline\"  >M\u00e9todo<\/h3><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_hr-3e128d09911abf776949821b39a02bfe\">\n#top .hr.av-av_hr-3e128d09911abf776949821b39a02bfe{\nmargin-top:10px;\nmargin-bottom:10px;\n}\n.hr.av-av_hr-3e128d09911abf776949821b39a02bfe .hr-inner{\nwidth:50px;\nborder-color:#efbb20;\n}\n<\/style>\n<div  class='hr av-av_hr-3e128d09911abf776949821b39a02bfe hr-custom  avia-builder-el-24  el_after_av_heading  el_before_av_textblock  hr-left hr-icon-no'><span class='hr-inner inner-border-av-border-fat'><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<section  class='av_textblock_section av-av_textblock-0366cc7376be6c9e82a3e9cc8987b64f '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p>Aulas te\u00f3ricas e estudo dirigido exta classe.<\/p>\n<\/div><\/section><\/p><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_full-d71a51a707c4656b37c9afbbd6138215\">\n.flex_column.av-av_one_full-d71a51a707c4656b37c9afbbd6138215{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_full-d71a51a707c4656b37c9afbbd6138215 av_one_full  avia-builder-el-26  el_after_av_one_full  el_before_av_one_full  first flex_column_div av-animated-generic bottom-to-top av-zero-column-padding  column-top-margin'     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_heading-917d56240629ea2032c2efb961203dce\">\n#top .av-special-heading.av-av_heading-917d56240629ea2032c2efb961203dce{\npadding-bottom:0;\n}\nbody .av-special-heading.av-av_heading-917d56240629ea2032c2efb961203dce .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-av_heading-917d56240629ea2032c2efb961203dce .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-av_heading-917d56240629ea2032c2efb961203dce av-special-heading-h3 blockquote modern-quote  avia-builder-el-27  el_before_av_hr  avia-builder-el-first '><h3 class='av-special-heading-tag '  itemprop=\"headline\"  > Avalia\u00e7\u00e3o<\/h3><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_hr-3e128d09911abf776949821b39a02bfe\">\n#top .hr.av-av_hr-3e128d09911abf776949821b39a02bfe{\nmargin-top:10px;\nmargin-bottom:10px;\n}\n.hr.av-av_hr-3e128d09911abf776949821b39a02bfe .hr-inner{\nwidth:50px;\nborder-color:#efbb20;\n}\n<\/style>\n<div  class='hr av-av_hr-3e128d09911abf776949821b39a02bfe hr-custom  avia-builder-el-28  el_after_av_heading  el_before_av_textblock  hr-left hr-icon-no'><span class='hr-inner inner-border-av-border-fat'><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<section  class='av_textblock_section av-av_textblock-0366cc7376be6c9e82a3e9cc8987b64f '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p>Estudo Dirigido (2): 30 pontos (15 pontos cada)<br \/>\nAvalia\u00e7\u00e3o te\u00f3rica: 40 pontos<br \/>\nParticipa\u00e7\u00e3o: 30 pontos<\/p>\n<p>Considerando as atividades te\u00f3ricas, os estudos dirigidos e a participa\u00e7\u00e3o, o aluno dever\u00e1 obter um valor m\u00ednimo de 60% no total das atividades. Crit\u00e9rios de Avalia\u00e7\u00e3o: Comportamento: Frequ\u00eancia, interesse, participa\u00e7\u00e3o e disponibilidade; Relacionamento: Colegas, professores e funcion\u00e1rios; Organiza\u00e7\u00e3o: Apresenta\u00e7\u00e3o dos estudos dirigidos; Desempenho te\u00f3rico: Capacidade para indicar e planejar os procedimentos do tratamento endod\u00f4ntico de molares, dentes permanentes jovens e\/ou traumatizados, uso do MTA e como proceder frente aos acidente e complica\u00e7\u00f5es decorrentes do tratamento endod\u00f4ntico.<\/p>\n<\/div><\/section><\/p><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_full-d71a51a707c4656b37c9afbbd6138215\">\n.flex_column.av-av_one_full-d71a51a707c4656b37c9afbbd6138215{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_full-d71a51a707c4656b37c9afbbd6138215 av_one_full  avia-builder-el-30  el_after_av_one_full  el_before_av_one_full  first flex_column_div av-animated-generic bottom-to-top av-zero-column-padding  column-top-margin'     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_heading-47214b53be4a8e5e253e57b06434cc20\">\n#top .av-special-heading.av-av_heading-47214b53be4a8e5e253e57b06434cc20{\npadding-bottom:0;\n}\nbody .av-special-heading.av-av_heading-47214b53be4a8e5e253e57b06434cc20 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-av_heading-47214b53be4a8e5e253e57b06434cc20 .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-av_heading-47214b53be4a8e5e253e57b06434cc20 av-special-heading-h3 blockquote modern-quote  avia-builder-el-31  el_before_av_hr  avia-builder-el-first '><h3 class='av-special-heading-tag '  itemprop=\"headline\"  >Cronograma<\/h3><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_hr-3e128d09911abf776949821b39a02bfe\">\n#top .hr.av-av_hr-3e128d09911abf776949821b39a02bfe{\nmargin-top:10px;\nmargin-bottom:10px;\n}\n.hr.av-av_hr-3e128d09911abf776949821b39a02bfe .hr-inner{\nwidth:50px;\nborder-color:#efbb20;\n}\n<\/style>\n<div  class='hr av-av_hr-3e128d09911abf776949821b39a02bfe hr-custom  avia-builder-el-32  el_after_av_heading  el_before_av_textblock  hr-left hr-icon-no'><span class='hr-inner inner-border-av-border-fat'><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<section  class='av_textblock_section av-av_textblock-0366cc7376be6c9e82a3e9cc8987b64f '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><table width=\"557\">\n<tbody>\n<tr>\n<td style=\"text-align: center\" colspan=\"2\" width=\"557\">Aulas te\u00f3ricas e estudo dirigido exta classe<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center\">Assunto<\/td>\n<td style=\"text-align: left\">Professor<\/td>\n<\/tr>\n<tr>\n<td>Limpeza e Formata\u00e7\u00e3o do SCR em Molares- 2h<\/td>\n<td>Ana Cec\u00edlia<\/td>\n<\/tr>\n<tr>\n<td>Utiliza\u00e7\u00e3o dos instrumentos rot\u00e1torios de NiTi em Endodontia 2h<\/td>\n<td>Guiomar<\/td>\n<\/tr>\n<tr>\n<td>Acidentes e complica\u00e7\u00f5es em Endodontia 2h<\/td>\n<td>Luiz Carlos<\/td>\n<\/tr>\n<tr>\n<td>Etiopatogenia das altera\u00e7\u00f5es periapicais 2h<\/td>\n<td>Ant\u00f4nio<\/td>\n<\/tr>\n<tr>\n<td>Traumatismos Dent\u00e1rios 2h<\/td>\n<td>Juliana<\/td>\n<\/tr>\n<tr>\n<td>Emprego do cimento MTA em Endodontia 2h<\/td>\n<td>Ana Cec\u00edlia<\/td>\n<\/tr>\n<tr>\n<td>Tratamento Endod\u00f4ntico de dentes permanentes jovens 2h<\/td>\n<td>K\u00e1tia<\/td>\n<\/tr>\n<tr>\n<td>Avalia\u00e7\u00e3o te\u00f3rica 1h<\/td>\n<td>K\u00e1tia<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left\">Estudos dirigidos I e II (Temas de atualiza\u00e7\u00e3o) Extra classe<\/td>\n<td style=\"text-align: center\">Juliana\/Elen<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div><\/section><\/p><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_full-d71a51a707c4656b37c9afbbd6138215\">\n.flex_column.av-av_one_full-d71a51a707c4656b37c9afbbd6138215{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_full-d71a51a707c4656b37c9afbbd6138215 av_one_full  avia-builder-el-34  el_after_av_one_full  el_before_av_one_full  first flex_column_div av-animated-generic bottom-to-top av-zero-column-padding  column-top-margin'     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_heading-d2cf3b96017e4960371cfff408d375f0\">\n#top .av-special-heading.av-av_heading-d2cf3b96017e4960371cfff408d375f0{\npadding-bottom:0;\n}\nbody .av-special-heading.av-av_heading-d2cf3b96017e4960371cfff408d375f0 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-av_heading-d2cf3b96017e4960371cfff408d375f0 .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-av_heading-d2cf3b96017e4960371cfff408d375f0 av-special-heading-h3 blockquote modern-quote  avia-builder-el-35  el_before_av_hr  avia-builder-el-first '><h3 class='av-special-heading-tag '  itemprop=\"headline\"  >Informa\u00e7\u00f5es Adicionais<\/h3><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_hr-3e128d09911abf776949821b39a02bfe\">\n#top .hr.av-av_hr-3e128d09911abf776949821b39a02bfe{\nmargin-top:10px;\nmargin-bottom:10px;\n}\n.hr.av-av_hr-3e128d09911abf776949821b39a02bfe .hr-inner{\nwidth:50px;\nborder-color:#efbb20;\n}\n<\/style>\n<div  class='hr av-av_hr-3e128d09911abf776949821b39a02bfe hr-custom  avia-builder-el-36  el_after_av_heading  el_before_av_textblock  hr-left hr-icon-no'><span class='hr-inner inner-border-av-border-fat'><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<section  class='av_textblock_section av-av_textblock-0366cc7376be6c9e82a3e9cc8987b64f '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p>Carga hor\u00e1ria (hs\/aula): 15h (Te\u00f3rica: 15h)<\/p>\n<p>Cr\u00e9ditos: 1<\/p>\n<\/div><\/section><\/p><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_full-d71a51a707c4656b37c9afbbd6138215\">\n.flex_column.av-av_one_full-d71a51a707c4656b37c9afbbd6138215{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_full-d71a51a707c4656b37c9afbbd6138215 av_one_full  avia-builder-el-38  el_after_av_one_full  avia-builder-el-last  first flex_column_div av-animated-generic bottom-to-top av-zero-column-padding  column-top-margin'     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_heading-f25365ac0df8e1c15d4411d6a7144392\">\n#top .av-special-heading.av-av_heading-f25365ac0df8e1c15d4411d6a7144392{\npadding-bottom:0;\n}\nbody .av-special-heading.av-av_heading-f25365ac0df8e1c15d4411d6a7144392 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-av_heading-f25365ac0df8e1c15d4411d6a7144392 .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-av_heading-f25365ac0df8e1c15d4411d6a7144392 av-special-heading-h3 blockquote modern-quote  avia-builder-el-39  el_before_av_hr  avia-builder-el-first '><h3 class='av-special-heading-tag '  itemprop=\"headline\"  >Refer\u00eancias<\/h3><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_hr-3e128d09911abf776949821b39a02bfe\">\n#top .hr.av-av_hr-3e128d09911abf776949821b39a02bfe{\nmargin-top:10px;\nmargin-bottom:10px;\n}\n.hr.av-av_hr-3e128d09911abf776949821b39a02bfe .hr-inner{\nwidth:50px;\nborder-color:#efbb20;\n}\n<\/style>\n<div  class='hr av-av_hr-3e128d09911abf776949821b39a02bfe hr-custom  avia-builder-el-40  el_after_av_heading  el_before_av_textblock  hr-left hr-icon-no'><span class='hr-inner inner-border-av-border-fat'><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<section  class='av_textblock_section av-av_textblock-0366cc7376be6c9e82a3e9cc8987b64f '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p>1) ANDREASEN, J.O; ANDREASEN, F.M. Texbook and color of Traumatic Injuries to the teeth 3\u00aa<br \/>\ned. Munksgaard: Compenhagen, 1994. 771p.<br \/>\n2) COHEN, Stephen; HARGREAVES, Kenneth M. Caminhos da polpa. 9. Ed. Rio de Janeiro:<br \/>\nMosby, elsevier, 2007.. 1079p.<br \/>\n3) DE DEUS, Q. Endodontia. 5\u00aa ed. Medsi: Rio de Janeiro, 1992. 695p.<br \/>\n4) ESTRELA, C., FIGUEIREDO, J. A. Endodontia- Princ\u00edpios biol\u00f3gicos e mec\u00e2nicos. Livraria<br \/>\nEditora Artes- M\u00e9dicas: S\u00e3o Paulo, 1999. 819p.<br \/>\n5) HARGREAVES, Kenneth M.; COHEN, Stephen; BERMAN, Louis H. Cohen Caminhos da Polpa.<br \/>\n10 ed. Rio de Janeiro: Elsevier, 2011. 900p.<br \/>\n6) INGLE, J.S.; BAKLAND, L. K. Endodontics. 4\u00aa ed. Wilians e Wilkins: Malven, 1994.<br \/>\n7) LOPES, H. P.; SIQUEIRA Jr. J.F. Endodontia: Biologia e T\u00e9cnica. 3 ed. Guanabara Koogan,<br \/>\n2010. 951p.<br \/>\n8) MACHADO, Manoel Eduardo de Lima. Endodontia: S\u00e3o Paulo: Santos, 2007. 488p.<br \/>\n9) RUDDLE, Clifford. Endodontic canal preparation: breakthrough cleaning and shaping strategies.<br \/>\nDent Today. 1994 Feb; 13(2): 44, 46, 48-9.<br \/>\n10) SIQUEIRA, J. F. J. Tratamento das Infec\u00e7\u00f5e Endod\u00f4nticas. Rio de Janeiro: medsi, 1997. 196p.<\/p>\n<p>PROFFIT, W. R. Ortodontia Contempor\u00e2nea. 3\u00aa ed. Rio de Janeiro: Guanabara Koogan, 2002. 677p.<\/p>\n<\/div><\/section><\/p><\/div><\/p>\n<\/div><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":3857,"comment_status":"open","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"footnotes":""},"tags":[],"portfolio_entries":[41,44],"class_list":["post-3728","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio_entries-disciplinas","portfolio_entries-optativas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tratamento Endod\u00f4ntico de Molares - Departamento de Odontologia Restauradora<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.odonto.ufmg.br\/odr\/disciplinas\/tratamento-endodontico-de-molares\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tratamento Endod\u00f4ntico de Molares - Departamento de Odontologia Restauradora\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.odonto.ufmg.br\/odr\/disciplinas\/tratamento-endodontico-de-molares\/\" \/>\n<meta property=\"og:site_name\" content=\"Departamento de Odontologia Restauradora\" \/>\n<meta property=\"article:modified_time\" content=\"2016-09-16T13:40:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.odonto.ufmg.br\/odr\/wp-content\/uploads\/sites\/7\/2016\/09\/Root-Canal.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"11 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/odr\\\/disciplinas\\\/tratamento-endodontico-de-molares\\\/\",\"url\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/odr\\\/disciplinas\\\/tratamento-endodontico-de-molares\\\/\",\"name\":\"Tratamento Endod\u00f4ntico de Molares - Departamento de Odontologia Restauradora\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/odr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/odr\\\/disciplinas\\\/tratamento-endodontico-de-molares\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/odr\\\/disciplinas\\\/tratamento-endodontico-de-molares\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/odr\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2016\\\/09\\\/Root-Canal.jpg\",\"datePublished\":\"2016-09-15T12:16:37+00:00\",\"dateModified\":\"2016-09-16T13:40:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/odr\\\/disciplinas\\\/tratamento-endodontico-de-molares\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.odonto.ufmg.br\\\/odr\\\/disciplinas\\\/tratamento-endodontico-de-molares\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/odr\\\/disciplinas\\\/tratamento-endodontico-de-molares\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/odr\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2016\\\/09\\\/Root-Canal.jpg\",\"contentUrl\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/odr\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2016\\\/09\\\/Root-Canal.jpg\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/odr\\\/disciplinas\\\/tratamento-endodontico-de-molares\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/odr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tratamento Endod\u00f4ntico de Molares\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/odr\\\/#website\",\"url\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/odr\\\/\",\"name\":\"Departamento de Odontologia Restauradora\",\"description\":\"Faculdade de Odontologia - Universidade Federal de Minas Gerais\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/odr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tratamento Endod\u00f4ntico de Molares - Departamento de Odontologia Restauradora","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.odonto.ufmg.br\/odr\/disciplinas\/tratamento-endodontico-de-molares\/","og_locale":"pt_BR","og_type":"article","og_title":"Tratamento Endod\u00f4ntico de Molares - Departamento de Odontologia Restauradora","og_url":"https:\/\/www.odonto.ufmg.br\/odr\/disciplinas\/tratamento-endodontico-de-molares\/","og_site_name":"Departamento de Odontologia Restauradora","article_modified_time":"2016-09-16T13:40:23+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/www.odonto.ufmg.br\/odr\/wp-content\/uploads\/sites\/7\/2016\/09\/Root-Canal.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"11 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.odonto.ufmg.br\/odr\/disciplinas\/tratamento-endodontico-de-molares\/","url":"https:\/\/www.odonto.ufmg.br\/odr\/disciplinas\/tratamento-endodontico-de-molares\/","name":"Tratamento Endod\u00f4ntico de Molares - Departamento de Odontologia Restauradora","isPartOf":{"@id":"https:\/\/www.odonto.ufmg.br\/odr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.odonto.ufmg.br\/odr\/disciplinas\/tratamento-endodontico-de-molares\/#primaryimage"},"image":{"@id":"https:\/\/www.odonto.ufmg.br\/odr\/disciplinas\/tratamento-endodontico-de-molares\/#primaryimage"},"thumbnailUrl":"https:\/\/www.odonto.ufmg.br\/odr\/wp-content\/uploads\/sites\/7\/2016\/09\/Root-Canal.jpg","datePublished":"2016-09-15T12:16:37+00:00","dateModified":"2016-09-16T13:40:23+00:00","breadcrumb":{"@id":"https:\/\/www.odonto.ufmg.br\/odr\/disciplinas\/tratamento-endodontico-de-molares\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.odonto.ufmg.br\/odr\/disciplinas\/tratamento-endodontico-de-molares\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.odonto.ufmg.br\/odr\/disciplinas\/tratamento-endodontico-de-molares\/#primaryimage","url":"https:\/\/www.odonto.ufmg.br\/odr\/wp-content\/uploads\/sites\/7\/2016\/09\/Root-Canal.jpg","contentUrl":"https:\/\/www.odonto.ufmg.br\/odr\/wp-content\/uploads\/sites\/7\/2016\/09\/Root-Canal.jpg","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.odonto.ufmg.br\/odr\/disciplinas\/tratamento-endodontico-de-molares\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.odonto.ufmg.br\/odr\/"},{"@type":"ListItem","position":2,"name":"Tratamento Endod\u00f4ntico de Molares"}]},{"@type":"WebSite","@id":"https:\/\/www.odonto.ufmg.br\/odr\/#website","url":"https:\/\/www.odonto.ufmg.br\/odr\/","name":"Departamento de Odontologia Restauradora","description":"Faculdade de Odontologia - Universidade Federal de Minas Gerais","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.odonto.ufmg.br\/odr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"}]}},"_links":{"self":[{"href":"https:\/\/www.odonto.ufmg.br\/odr\/wp-json\/wp\/v2\/portfolio\/3728","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.odonto.ufmg.br\/odr\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/www.odonto.ufmg.br\/odr\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/www.odonto.ufmg.br\/odr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.odonto.ufmg.br\/odr\/wp-json\/wp\/v2\/comments?post=3728"}],"version-history":[{"count":1,"href":"https:\/\/www.odonto.ufmg.br\/odr\/wp-json\/wp\/v2\/portfolio\/3728\/revisions"}],"predecessor-version":[{"id":3858,"href":"https:\/\/www.odonto.ufmg.br\/odr\/wp-json\/wp\/v2\/portfolio\/3728\/revisions\/3858"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.odonto.ufmg.br\/odr\/wp-json\/wp\/v2\/media\/3857"}],"wp:attachment":[{"href":"https:\/\/www.odonto.ufmg.br\/odr\/wp-json\/wp\/v2\/media?parent=3728"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.odonto.ufmg.br\/odr\/wp-json\/wp\/v2\/tags?post=3728"},{"taxonomy":"portfolio_entries","embeddable":true,"href":"https:\/\/www.odonto.ufmg.br\/odr\/wp-json\/wp\/v2\/portfolio_entries?post=3728"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}