{"id":3725,"date":"2016-09-15T09:15:12","date_gmt":"2016-09-15T12:15:12","guid":{"rendered":"https:\/\/www.odonto.ufmg.br\/odr\/?post_type=portfolio&#038;p=3725"},"modified":"2016-09-16T10:03:36","modified_gmt":"2016-09-16T13:03:36","slug":"dentistica-iii","status":"publish","type":"portfolio","link":"https:\/\/www.odonto.ufmg.br\/odr\/disciplinas\/dentistica-iii\/","title":{"rendered":"Dent\u00edstica III"},"content":{"rendered":"\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_section-004808d8c1f4eaf1fc306a0e3041d6cb\">\n.avia-section.av-av_section-004808d8c1f4eaf1fc306a0e3041d6cb .av-parallax .av-parallax-inner{\nbackground-repeat:no-repeat;\nbackground-image:url(https:\/\/www.odonto.ufmg.br\/odr\/wp-content\/uploads\/sites\/7\/2016\/09\/images-21.jpg);\nbackground-position:50% 50%;\nbackground-attachment:scroll;\n}\n.avia-section.av-av_section-004808d8c1f4eaf1fc306a0e3041d6cb .av-section-color-overlay{\nopacity:0.5;\nbackground-color:#000000;\n}\n<\/style>\n<div id='av_section_1'  class='avia-section av-av_section-004808d8c1f4eaf1fc306a0e3041d6cb main_color avia-section-default avia-no-shadow  avia-builder-el-0  el_before_av_layout_row  avia-builder-el-first  avia-full-stretch av-parallax-section avia-bg-style-parallax av-section-color-overlay-active av-minimum-height av-minimum-height-50 av-height-50  container_wrap fullsize'  data-section-bg-repeat='stretch' data-av_minimum_height_pc='50' data-av_min_height_opt='50'><div class='av-parallax' data-avia-parallax-ratio='0.3' ><div class='av-parallax-inner main_color avia-full-stretch'><\/div><\/div><div class=\"av-section-color-overlay-wrap\"><div class=\"av-section-color-overlay\"><\/div><a href='#next-section' title='' class='scroll-down-link  avia-svg-icon avia-font-svg_entypo-fontello' data-av_svg_icon='down-open-mini' data-av_iconset='svg_entypo-fontello'><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15\" height=\"32\" viewBox=\"0 0 15 32\" preserveAspectRatio=\"xMidYMid meet\" aria-labelledby='av-svg-title-1' aria-describedby='av-svg-desc-1' role=\"graphics-symbol\" aria-hidden=\"true\">\n<title id='av-svg-title-1'>Scroll to next section<\/title>\n<desc id='av-svg-desc-1'>Scroll to next section<\/desc>\n<path d=\"M12.96 12.16q0.704-0.832 1.536 0 0.832 0.704 0 1.536l-6.272 6.144q-0.704 0.704-1.536 0l-6.272-6.144q-0.832-0.832 0-1.536 0.768-0.768 1.6 0l5.44 4.992z\"><\/path>\n<\/svg><\/a><div class='container av-section-cont-open' ><main  role=\"main\" itemprop=\"mainContentOfPage\"  class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-3725'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_full-d71a51a707c4656b37c9afbbd6138215\">\n.flex_column.av-av_one_full-d71a51a707c4656b37c9afbbd6138215{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_full-d71a51a707c4656b37c9afbbd6138215 av_one_full  avia-builder-el-1  avia-builder-el-no-sibling  first flex_column_div av-animated-generic bottom-to-top av-zero-column-padding  '     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_heading-e2800c0c2ab41c5de92fe9a46c2d0c1d\">\n#top .av-special-heading.av-av_heading-e2800c0c2ab41c5de92fe9a46c2d0c1d{\npadding-bottom:0;\ncolor:#ffffff;\nfont-size:40px;\n}\nbody .av-special-heading.av-av_heading-e2800c0c2ab41c5de92fe9a46c2d0c1d .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n#top #wrap_all .av-special-heading.av-av_heading-e2800c0c2ab41c5de92fe9a46c2d0c1d .av-special-heading-tag{\nfont-size:40px;\n}\n.av-special-heading.av-av_heading-e2800c0c2ab41c5de92fe9a46c2d0c1d .special-heading-inner-border{\nborder-color:#ffffff;\n}\n.av-special-heading.av-av_heading-e2800c0c2ab41c5de92fe9a46c2d0c1d .av-subheading{\nfont-size:40px;\n}\n\n@media only screen and (min-width: 480px) and (max-width: 767px){ \n#top #wrap_all .av-special-heading.av-av_heading-e2800c0c2ab41c5de92fe9a46c2d0c1d .av-special-heading-tag{\nfont-size:0.8em;\n}\n}\n\n@media only screen and (max-width: 479px){ \n#top #wrap_all .av-special-heading.av-av_heading-e2800c0c2ab41c5de92fe9a46c2d0c1d .av-special-heading-tag{\nfont-size:0.8em;\n}\n}\n<\/style>\n<div  class='av-special-heading av-av_heading-e2800c0c2ab41c5de92fe9a46c2d0c1d av-special-heading-h3 custom-color-heading blockquote modern-quote modern-centered  avia-builder-el-2  el_before_av_hr  avia-builder-el-first  av-inherit-size'><h3 class='av-special-heading-tag '  itemprop=\"headline\"  >Dent\u00edstica III<\/h3><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_hr-c282f4cd9bd3f3c176a54b23e2e441a5\">\n#top .hr.av-av_hr-c282f4cd9bd3f3c176a54b23e2e441a5{\nmargin-top:5px;\nmargin-bottom:35px;\n}\n.hr.av-av_hr-c282f4cd9bd3f3c176a54b23e2e441a5 .hr-inner{\nwidth:50px;\nborder-color:#efbb20;\n}\n<\/style>\n<div  class='hr av-av_hr-c282f4cd9bd3f3c176a54b23e2e441a5 hr-custom  avia-builder-el-3  el_after_av_heading  avia-builder-el-last  hr-center hr-icon-no'><span class='hr-inner inner-border-av-border-fat'><span class=\"hr-inner-style\"><\/span><\/span><\/div><\/p><\/div>\n\n<\/div><\/div><\/main><!-- close content main element --><\/div><\/div><\/div><div id='av-layout-grid-1'  class='av-layout-grid-container av-av_layout_row-d33986b140bd8e03ac046ce4e36b6832 entry-content-wrapper main_color av-flex-cells  avia-builder-el-4  el_after_av_section  avia-builder-el-last  grid-row-not-first  container_wrap fullsize'  >\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_cell_one_full-e00c26a1a439f0f470fd6e7e74fa6685\">\n.flex_cell.av-av_cell_one_full-e00c26a1a439f0f470fd6e7e74fa6685{\nvertical-align:middle;\nheight:400px;\nmin-height:400px;\n}\n.responsive #top #wrap_all .flex_cell.av-av_cell_one_full-e00c26a1a439f0f470fd6e7e74fa6685{\npadding:60px 60px 60px 60px !important;\n}\n<\/style>\n<div class='flex_cell av-av_cell_one_full-e00c26a1a439f0f470fd6e7e74fa6685 av-gridrow-cell av_one_full no_margin  avia-builder-el-5  avia-builder-el-no-sibling  content-align-middle'  ><div class='flex_cell_inner'><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_full-d71a51a707c4656b37c9afbbd6138215\">\n.flex_column.av-av_one_full-d71a51a707c4656b37c9afbbd6138215{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_full-d71a51a707c4656b37c9afbbd6138215 av_one_full  avia-builder-el-6  el_before_av_one_full  avia-builder-el-first  first flex_column_div av-animated-generic bottom-to-top av-zero-column-padding  '     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_heading-c7ba9dc5db7c4e479e170540dcc1013f\">\n#top .av-special-heading.av-av_heading-c7ba9dc5db7c4e479e170540dcc1013f{\npadding-bottom:0;\n}\nbody .av-special-heading.av-av_heading-c7ba9dc5db7c4e479e170540dcc1013f .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-av_heading-c7ba9dc5db7c4e479e170540dcc1013f .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-av_heading-c7ba9dc5db7c4e479e170540dcc1013f av-special-heading-h3 blockquote modern-quote  avia-builder-el-7  el_before_av_hr  avia-builder-el-first '><h3 class='av-special-heading-tag '  itemprop=\"headline\"  >Objetivo Geral<\/h3><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_hr-3e128d09911abf776949821b39a02bfe\">\n#top .hr.av-av_hr-3e128d09911abf776949821b39a02bfe{\nmargin-top:10px;\nmargin-bottom:10px;\n}\n.hr.av-av_hr-3e128d09911abf776949821b39a02bfe .hr-inner{\nwidth:50px;\nborder-color:#efbb20;\n}\n<\/style>\n<div  class='hr av-av_hr-3e128d09911abf776949821b39a02bfe hr-custom  avia-builder-el-8  el_after_av_heading  el_before_av_textblock  hr-left hr-icon-no'><span class='hr-inner inner-border-av-border-fat'><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<section  class='av_textblock_section av-av_textblock-0366cc7376be6c9e82a3e9cc8987b64f '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p>Desenvolver habilidades no aluno para realizar n\u00facleos met\u00e1licos fundidos e coroas unit\u00e1rias em pacientes, baseado em evid\u00eancias cient\u00edficas.<\/p>\n<\/div><\/section><\/p><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_full-d71a51a707c4656b37c9afbbd6138215\">\n.flex_column.av-av_one_full-d71a51a707c4656b37c9afbbd6138215{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_full-d71a51a707c4656b37c9afbbd6138215 av_one_full  avia-builder-el-10  el_after_av_one_full  el_before_av_one_full  first flex_column_div av-animated-generic bottom-to-top av-zero-column-padding  column-top-margin'     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_heading-effd6a08769ec93046a81ac9e6a6a0c1\">\n#top .av-special-heading.av-av_heading-effd6a08769ec93046a81ac9e6a6a0c1{\npadding-bottom:0;\n}\nbody .av-special-heading.av-av_heading-effd6a08769ec93046a81ac9e6a6a0c1 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-av_heading-effd6a08769ec93046a81ac9e6a6a0c1 .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-av_heading-effd6a08769ec93046a81ac9e6a6a0c1 av-special-heading-h3 blockquote modern-quote  avia-builder-el-11  el_before_av_hr  avia-builder-el-first '><h3 class='av-special-heading-tag '  itemprop=\"headline\"  >Objetivos Espec\u00edficos<\/h3><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_hr-3e128d09911abf776949821b39a02bfe\">\n#top .hr.av-av_hr-3e128d09911abf776949821b39a02bfe{\nmargin-top:10px;\nmargin-bottom:10px;\n}\n.hr.av-av_hr-3e128d09911abf776949821b39a02bfe .hr-inner{\nwidth:50px;\nborder-color:#efbb20;\n}\n<\/style>\n<div  class='hr av-av_hr-3e128d09911abf776949821b39a02bfe hr-custom  avia-builder-el-12  el_after_av_heading  el_before_av_textblock  hr-left hr-icon-no'><span class='hr-inner inner-border-av-border-fat'><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<section  class='av_textblock_section av-av_textblock-0366cc7376be6c9e82a3e9cc8987b64f '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><ul>\n<li>Realizar procedimentos de promo\u00e7\u00e3o de sa\u00fade bucal, como educa\u00e7\u00e3o, orienta\u00e7\u00e3o de sa\u00fade bucal e de dieta.<\/li>\n<li>Realizar procedimentos periodontais de raspagem e polimento coron\u00e1rio.<\/li>\n<li>Realizar a confec\u00e7\u00e3o de n\u00facleos e coroas unit\u00e1rias. Encaminhar os pacientes para as especialidades, quando necess\u00e1rio.<\/li>\n<li>Ampliar as oportunidades de estudo e pr\u00e1tica odontol\u00f3gica aos alunos da gradua\u00e7\u00e3o.<\/li>\n<li>Imers\u00e3o do acad\u00eamico na inicia\u00e7\u00e3o cient\u00edfica, visando a produ\u00e7\u00e3o de conhecimentos e artigos cient\u00edficos e apresenta\u00e7\u00e3o em eventos.<\/li>\n<\/ul>\n<\/div><\/section><\/p><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_full-d71a51a707c4656b37c9afbbd6138215\">\n.flex_column.av-av_one_full-d71a51a707c4656b37c9afbbd6138215{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_full-d71a51a707c4656b37c9afbbd6138215 av_one_full  avia-builder-el-14  el_after_av_one_full  el_before_av_one_full  first flex_column_div av-animated-generic bottom-to-top av-zero-column-padding  column-top-margin'     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_heading-863998279fddca80855a9192a7018520\">\n#top .av-special-heading.av-av_heading-863998279fddca80855a9192a7018520{\npadding-bottom:0;\n}\nbody .av-special-heading.av-av_heading-863998279fddca80855a9192a7018520 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-av_heading-863998279fddca80855a9192a7018520 .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-av_heading-863998279fddca80855a9192a7018520 av-special-heading-h3 blockquote modern-quote  avia-builder-el-15  el_before_av_hr  avia-builder-el-first '><h3 class='av-special-heading-tag '  itemprop=\"headline\"  >Ementa<\/h3><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_hr-3e128d09911abf776949821b39a02bfe\">\n#top .hr.av-av_hr-3e128d09911abf776949821b39a02bfe{\nmargin-top:10px;\nmargin-bottom:10px;\n}\n.hr.av-av_hr-3e128d09911abf776949821b39a02bfe .hr-inner{\nwidth:50px;\nborder-color:#efbb20;\n}\n<\/style>\n<div  class='hr av-av_hr-3e128d09911abf776949821b39a02bfe hr-custom  avia-builder-el-16  el_after_av_heading  el_before_av_textblock  hr-left hr-icon-no'><span class='hr-inner inner-border-av-border-fat'><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<section  class='av_textblock_section av-av_textblock-0366cc7376be6c9e82a3e9cc8987b64f '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p>Conhecimento te\u00f3rico\/pr\u00e1tico tanto em manequim quanto na cl\u00ednica para a realiza\u00e7\u00e3o de coroas unit\u00e1rias e n\u00facleos met\u00e1licos fundidos em pacientes dentados ou parcialmente desdentados.<\/p>\n<\/div><\/section><\/p><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_full-d71a51a707c4656b37c9afbbd6138215\">\n.flex_column.av-av_one_full-d71a51a707c4656b37c9afbbd6138215{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_full-d71a51a707c4656b37c9afbbd6138215 av_one_full  avia-builder-el-18  el_after_av_one_full  el_before_av_one_full  first flex_column_div av-animated-generic bottom-to-top av-zero-column-padding  column-top-margin'     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_heading-3ba08d5caab19681a5019580dbd617bc\">\n#top .av-special-heading.av-av_heading-3ba08d5caab19681a5019580dbd617bc{\npadding-bottom:0;\n}\nbody .av-special-heading.av-av_heading-3ba08d5caab19681a5019580dbd617bc .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-av_heading-3ba08d5caab19681a5019580dbd617bc .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-av_heading-3ba08d5caab19681a5019580dbd617bc av-special-heading-h3 blockquote modern-quote  avia-builder-el-19  el_before_av_hr  avia-builder-el-first '><h3 class='av-special-heading-tag '  itemprop=\"headline\"  > Conte\u00fado<\/h3><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_hr-3e128d09911abf776949821b39a02bfe\">\n#top .hr.av-av_hr-3e128d09911abf776949821b39a02bfe{\nmargin-top:10px;\nmargin-bottom:10px;\n}\n.hr.av-av_hr-3e128d09911abf776949821b39a02bfe .hr-inner{\nwidth:50px;\nborder-color:#efbb20;\n}\n<\/style>\n<div  class='hr av-av_hr-3e128d09911abf776949821b39a02bfe hr-custom  avia-builder-el-20  el_after_av_heading  el_before_av_textblock  hr-left hr-icon-no'><span class='hr-inner inner-border-av-border-fat'><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_textblock-8e5bdedebac81bcd937ed355ccd26d60\">\n#top .av_textblock_section.av-av_textblock-8e5bdedebac81bcd937ed355ccd26d60 .avia_textblock{\ncolor:#000000;\n}\n<\/style>\n<section  class='av_textblock_section av-av_textblock-8e5bdedebac81bcd937ed355ccd26d60 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock av_inherit_color'  itemprop=\"text\" ><ul>\n<li>N\u00facleos met\u00e1licos fundidos<\/li>\n<li>Preparo cavit\u00e1rios para coroas<\/li>\n<li>Coroas provis\u00f3rias<\/li>\n<li>Moldagem com casquete<\/li>\n<li>Preparo cavit\u00e1rios para coroas cer\u00e2micas puras<\/li>\n<li>Cer\u00e2micas &#8211; caracteriza\u00e7\u00f5es de sistemas.<\/li>\n<\/ul>\n<\/div><\/section><\/p><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_full-d71a51a707c4656b37c9afbbd6138215\">\n.flex_column.av-av_one_full-d71a51a707c4656b37c9afbbd6138215{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_full-d71a51a707c4656b37c9afbbd6138215 av_one_full  avia-builder-el-22  el_after_av_one_full  el_before_av_one_full  first flex_column_div av-animated-generic bottom-to-top av-zero-column-padding  column-top-margin'     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_heading-917d56240629ea2032c2efb961203dce\">\n#top .av-special-heading.av-av_heading-917d56240629ea2032c2efb961203dce{\npadding-bottom:0;\n}\nbody .av-special-heading.av-av_heading-917d56240629ea2032c2efb961203dce .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-av_heading-917d56240629ea2032c2efb961203dce .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-av_heading-917d56240629ea2032c2efb961203dce av-special-heading-h3 blockquote modern-quote  avia-builder-el-23  el_before_av_hr  avia-builder-el-first '><h3 class='av-special-heading-tag '  itemprop=\"headline\"  > Avalia\u00e7\u00e3o<\/h3><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_hr-3e128d09911abf776949821b39a02bfe\">\n#top .hr.av-av_hr-3e128d09911abf776949821b39a02bfe{\nmargin-top:10px;\nmargin-bottom:10px;\n}\n.hr.av-av_hr-3e128d09911abf776949821b39a02bfe .hr-inner{\nwidth:50px;\nborder-color:#efbb20;\n}\n<\/style>\n<div  class='hr av-av_hr-3e128d09911abf776949821b39a02bfe hr-custom  avia-builder-el-24  el_after_av_heading  el_before_av_textblock  hr-left hr-icon-no'><span class='hr-inner inner-border-av-border-fat'><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<section  class='av_textblock_section av-av_textblock-0366cc7376be6c9e82a3e9cc8987b64f '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p><strong>Provas te\u00f3ricas:<\/strong> 60 pontos (3 provas de 20 pontos cada). A \u00faltima prova ser\u00e1 de toda a mat\u00e9ria ministrada.<\/p>\n<p><strong>Avalia\u00e7\u00e3o pr\u00e1tica:<\/strong> 40 pontos.<\/p>\n<p><strong>Total:<\/strong> 100 pontos<\/p>\n<\/div><\/section><\/p><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_full-d71a51a707c4656b37c9afbbd6138215\">\n.flex_column.av-av_one_full-d71a51a707c4656b37c9afbbd6138215{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_full-d71a51a707c4656b37c9afbbd6138215 av_one_full  avia-builder-el-26  el_after_av_one_full  el_before_av_one_full  first flex_column_div av-animated-generic bottom-to-top av-zero-column-padding  column-top-margin'     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_heading-47214b53be4a8e5e253e57b06434cc20\">\n#top .av-special-heading.av-av_heading-47214b53be4a8e5e253e57b06434cc20{\npadding-bottom:0;\n}\nbody .av-special-heading.av-av_heading-47214b53be4a8e5e253e57b06434cc20 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-av_heading-47214b53be4a8e5e253e57b06434cc20 .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-av_heading-47214b53be4a8e5e253e57b06434cc20 av-special-heading-h3 blockquote modern-quote  avia-builder-el-27  el_before_av_hr  avia-builder-el-first '><h3 class='av-special-heading-tag '  itemprop=\"headline\"  >Cronograma<\/h3><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_hr-3e128d09911abf776949821b39a02bfe\">\n#top .hr.av-av_hr-3e128d09911abf776949821b39a02bfe{\nmargin-top:10px;\nmargin-bottom:10px;\n}\n.hr.av-av_hr-3e128d09911abf776949821b39a02bfe .hr-inner{\nwidth:50px;\nborder-color:#efbb20;\n}\n<\/style>\n<div  class='hr av-av_hr-3e128d09911abf776949821b39a02bfe hr-custom  avia-builder-el-28  el_after_av_heading  el_before_av_textblock  hr-left hr-icon-no'><span class='hr-inner inner-border-av-border-fat'><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<section  class='av_textblock_section av-av_textblock-0366cc7376be6c9e82a3e9cc8987b64f '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p>A ser definido pelo Colegiado de Gradua\u00e7\u00e3o e com as demais disciplinas do m\u00f3dulo.<\/p>\n<\/div><\/section><\/p><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_full-d71a51a707c4656b37c9afbbd6138215\">\n.flex_column.av-av_one_full-d71a51a707c4656b37c9afbbd6138215{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_full-d71a51a707c4656b37c9afbbd6138215 av_one_full  avia-builder-el-30  el_after_av_one_full  el_before_av_one_full  first flex_column_div av-animated-generic bottom-to-top av-zero-column-padding  column-top-margin'     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_heading-d2cf3b96017e4960371cfff408d375f0\">\n#top .av-special-heading.av-av_heading-d2cf3b96017e4960371cfff408d375f0{\npadding-bottom:0;\n}\nbody .av-special-heading.av-av_heading-d2cf3b96017e4960371cfff408d375f0 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-av_heading-d2cf3b96017e4960371cfff408d375f0 .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-av_heading-d2cf3b96017e4960371cfff408d375f0 av-special-heading-h3 blockquote modern-quote  avia-builder-el-31  el_before_av_hr  avia-builder-el-first '><h3 class='av-special-heading-tag '  itemprop=\"headline\"  >Informa\u00e7\u00f5es Adicionais<\/h3><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_hr-3e128d09911abf776949821b39a02bfe\">\n#top .hr.av-av_hr-3e128d09911abf776949821b39a02bfe{\nmargin-top:10px;\nmargin-bottom:10px;\n}\n.hr.av-av_hr-3e128d09911abf776949821b39a02bfe .hr-inner{\nwidth:50px;\nborder-color:#efbb20;\n}\n<\/style>\n<div  class='hr av-av_hr-3e128d09911abf776949821b39a02bfe hr-custom  avia-builder-el-32  el_after_av_heading  el_before_av_textblock  hr-left hr-icon-no'><span class='hr-inner inner-border-av-border-fat'><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<section  class='av_textblock_section av-av_textblock-0366cc7376be6c9e82a3e9cc8987b64f '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p>Turma: 7\u00ba per\u00edodo<\/p>\n<p>Carga hor\u00e1ria (hs\/aula): 75\u00a0horas (15\u00a0te\u00f3rica e 60\u00a0pr\u00e1tica)<\/p>\n<p>Cr\u00e9ditos: 5<\/p>\n<\/div><\/section><\/p><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_full-d71a51a707c4656b37c9afbbd6138215\">\n.flex_column.av-av_one_full-d71a51a707c4656b37c9afbbd6138215{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_full-d71a51a707c4656b37c9afbbd6138215 av_one_full  avia-builder-el-34  el_after_av_one_full  avia-builder-el-last  first flex_column_div av-animated-generic bottom-to-top av-zero-column-padding  column-top-margin'     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_heading-f25365ac0df8e1c15d4411d6a7144392\">\n#top .av-special-heading.av-av_heading-f25365ac0df8e1c15d4411d6a7144392{\npadding-bottom:0;\n}\nbody .av-special-heading.av-av_heading-f25365ac0df8e1c15d4411d6a7144392 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-av_heading-f25365ac0df8e1c15d4411d6a7144392 .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-av_heading-f25365ac0df8e1c15d4411d6a7144392 av-special-heading-h3 blockquote modern-quote  avia-builder-el-35  el_before_av_hr  avia-builder-el-first '><h3 class='av-special-heading-tag '  itemprop=\"headline\"  >Refer\u00eancias<\/h3><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_hr-3e128d09911abf776949821b39a02bfe\">\n#top .hr.av-av_hr-3e128d09911abf776949821b39a02bfe{\nmargin-top:10px;\nmargin-bottom:10px;\n}\n.hr.av-av_hr-3e128d09911abf776949821b39a02bfe .hr-inner{\nwidth:50px;\nborder-color:#efbb20;\n}\n<\/style>\n<div  class='hr av-av_hr-3e128d09911abf776949821b39a02bfe hr-custom  avia-builder-el-36  el_after_av_heading  el_before_av_textblock  hr-left hr-icon-no'><span class='hr-inner inner-border-av-border-fat'><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<section  class='av_textblock_section av-av_textblock-0366cc7376be6c9e82a3e9cc8987b64f '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p>BARATIERI, L. N. Odontologia Restauradora \u2013 Fundamentos e possibilidades. S\u00e3o Paulo: Santos, 2001. 739p.<\/p>\n<p>BARATIERI, L. N. Solu\u00e7\u00f5es Cl\u00ednicas \u2013 Fundamentos e T\u00e9cnicas. Florian\u00f3polis: 2008. 601p.<\/p>\n<p>BARATIERI, L N. MONTEIRO Jr., MELO, T. S. Odontologia Restauradora \u2013 Fundamentos e T\u00e9cnicas. S\u00e3o Paulo: Editora Santos. 2010. 761p.<\/p>\n<p>BUSATO, A L S. Dent\u00edstica \u2013 Filosofia, Conceitos e Pr\u00e1tica Cl\u00ednica \u2013 S\u00e3o Paulo: Artes M\u00e9dicas, 2005. 377p.<\/p>\n<p>CONCEI\u00c7\u00c3O, E N. Dent\u00edstica \u2013 Sa\u00fade e Est\u00e9tica. Porto Alegre: Artmed, 2000.346p.<\/p>\n<p>CONCEI\u00c7\u00c3O, E N. Restaura\u00e7\u00f5es Est\u00e9ticas \u2013 Comp\u00f3sitos, Cer\u00e2micas e Implantes. Porto Alegre: Artmed, 2005. 304p.<\/p>\n<p>MONDELLI, J. Dent\u00edstica \u2013 Procedimentos Pr\u00e9-Cl\u00ednicos . S\u00e3o Paulo: Premier, 1998. 260p.<\/p>\n<p>STURDEVANT, C. M. Arte Y Ciencia de la Operatoria Dental . Buenos Aires: Panamericana, 1987. 765p.<\/p>\n<p>Summitt JB, Robbins JW, Schwartz RS. Fundamentals of Operative Dentistry: A Contemporary Approach. Quintessence Books, 2006. 612p.<\/p>\n<\/div><\/section><\/p><\/div><\/p>\n<\/div><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":3847,"comment_status":"open","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"footnotes":""},"tags":[],"portfolio_entries":[41,43],"class_list":["post-3725","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio_entries-disciplinas","portfolio_entries-obrigatorias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dent\u00edstica III - Departamento de Odontologia Restauradora<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.odonto.ufmg.br\/odr\/disciplinas\/dentistica-iii\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dent\u00edstica III - Departamento de Odontologia Restauradora\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.odonto.ufmg.br\/odr\/disciplinas\/dentistica-iii\/\" \/>\n<meta property=\"og:site_name\" content=\"Departamento de Odontologia Restauradora\" \/>\n<meta property=\"article:modified_time\" content=\"2016-09-16T13:03:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.odonto.ufmg.br\/odr\/wp-content\/uploads\/sites\/7\/2016\/09\/images-21.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"291\" \/>\n\t<meta property=\"og:image:height\" content=\"173\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/odr\\\/disciplinas\\\/dentistica-iii\\\/\",\"url\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/odr\\\/disciplinas\\\/dentistica-iii\\\/\",\"name\":\"Dent\u00edstica III - Departamento de Odontologia Restauradora\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/odr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/odr\\\/disciplinas\\\/dentistica-iii\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/odr\\\/disciplinas\\\/dentistica-iii\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/odr\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2016\\\/09\\\/images-21.jpg\",\"datePublished\":\"2016-09-15T12:15:12+00:00\",\"dateModified\":\"2016-09-16T13:03:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/odr\\\/disciplinas\\\/dentistica-iii\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.odonto.ufmg.br\\\/odr\\\/disciplinas\\\/dentistica-iii\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/odr\\\/disciplinas\\\/dentistica-iii\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/odr\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2016\\\/09\\\/images-21.jpg\",\"contentUrl\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/odr\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2016\\\/09\\\/images-21.jpg\",\"width\":291,\"height\":173},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/odr\\\/disciplinas\\\/dentistica-iii\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/odr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dent\u00edstica III\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/odr\\\/#website\",\"url\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/odr\\\/\",\"name\":\"Departamento de Odontologia Restauradora\",\"description\":\"Faculdade de Odontologia - Universidade Federal de Minas Gerais\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.odonto.ufmg.br\\\/odr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dent\u00edstica III - Departamento de Odontologia Restauradora","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.odonto.ufmg.br\/odr\/disciplinas\/dentistica-iii\/","og_locale":"pt_BR","og_type":"article","og_title":"Dent\u00edstica III - Departamento de Odontologia Restauradora","og_url":"https:\/\/www.odonto.ufmg.br\/odr\/disciplinas\/dentistica-iii\/","og_site_name":"Departamento de Odontologia Restauradora","article_modified_time":"2016-09-16T13:03:36+00:00","og_image":[{"width":291,"height":173,"url":"https:\/\/www.odonto.ufmg.br\/odr\/wp-content\/uploads\/sites\/7\/2016\/09\/images-21.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.odonto.ufmg.br\/odr\/disciplinas\/dentistica-iii\/","url":"https:\/\/www.odonto.ufmg.br\/odr\/disciplinas\/dentistica-iii\/","name":"Dent\u00edstica III - Departamento de Odontologia Restauradora","isPartOf":{"@id":"https:\/\/www.odonto.ufmg.br\/odr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.odonto.ufmg.br\/odr\/disciplinas\/dentistica-iii\/#primaryimage"},"image":{"@id":"https:\/\/www.odonto.ufmg.br\/odr\/disciplinas\/dentistica-iii\/#primaryimage"},"thumbnailUrl":"https:\/\/www.odonto.ufmg.br\/odr\/wp-content\/uploads\/sites\/7\/2016\/09\/images-21.jpg","datePublished":"2016-09-15T12:15:12+00:00","dateModified":"2016-09-16T13:03:36+00:00","breadcrumb":{"@id":"https:\/\/www.odonto.ufmg.br\/odr\/disciplinas\/dentistica-iii\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.odonto.ufmg.br\/odr\/disciplinas\/dentistica-iii\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.odonto.ufmg.br\/odr\/disciplinas\/dentistica-iii\/#primaryimage","url":"https:\/\/www.odonto.ufmg.br\/odr\/wp-content\/uploads\/sites\/7\/2016\/09\/images-21.jpg","contentUrl":"https:\/\/www.odonto.ufmg.br\/odr\/wp-content\/uploads\/sites\/7\/2016\/09\/images-21.jpg","width":291,"height":173},{"@type":"BreadcrumbList","@id":"https:\/\/www.odonto.ufmg.br\/odr\/disciplinas\/dentistica-iii\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.odonto.ufmg.br\/odr\/"},{"@type":"ListItem","position":2,"name":"Dent\u00edstica III"}]},{"@type":"WebSite","@id":"https:\/\/www.odonto.ufmg.br\/odr\/#website","url":"https:\/\/www.odonto.ufmg.br\/odr\/","name":"Departamento de Odontologia Restauradora","description":"Faculdade de Odontologia - Universidade Federal de Minas Gerais","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.odonto.ufmg.br\/odr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"}]}},"_links":{"self":[{"href":"https:\/\/www.odonto.ufmg.br\/odr\/wp-json\/wp\/v2\/portfolio\/3725","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.odonto.ufmg.br\/odr\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/www.odonto.ufmg.br\/odr\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/www.odonto.ufmg.br\/odr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.odonto.ufmg.br\/odr\/wp-json\/wp\/v2\/comments?post=3725"}],"version-history":[{"count":1,"href":"https:\/\/www.odonto.ufmg.br\/odr\/wp-json\/wp\/v2\/portfolio\/3725\/revisions"}],"predecessor-version":[{"id":3816,"href":"https:\/\/www.odonto.ufmg.br\/odr\/wp-json\/wp\/v2\/portfolio\/3725\/revisions\/3816"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.odonto.ufmg.br\/odr\/wp-json\/wp\/v2\/media\/3847"}],"wp:attachment":[{"href":"https:\/\/www.odonto.ufmg.br\/odr\/wp-json\/wp\/v2\/media?parent=3725"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.odonto.ufmg.br\/odr\/wp-json\/wp\/v2\/tags?post=3725"},{"taxonomy":"portfolio_entries","embeddable":true,"href":"https:\/\/www.odonto.ufmg.br\/odr\/wp-json\/wp\/v2\/portfolio_entries?post=3725"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}